{"id":528,"date":"2022-12-14T10:51:38","date_gmt":"2022-12-14T10:51:38","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=sala&#038;p=528"},"modified":"2025-10-10T10:19:10","modified_gmt":"2025-10-10T08:19:10","slug":"sala-sinopoli","status":"publish","type":"sala","link":"https:\/\/www.auditorium.com\/it\/sala\/sala-sinopoli\/","title":{"rendered":"Sala Sinopoli"},"content":{"rendered":"<p>Dedicata al grande compositore e direttore d&#8217;orchestra Giuseppe Sinopoli, la Sala Sinopoli dell\u2019Auditorium ha una configurazione modulabile e garantisce allo spettatore una visibilit\u00e0 e una qualit\u00e0 del suono ottimali. Caratterizzata da una grande flessibilit\u00e0 distributiva e dimensioni adattabili, consente differenti possibilit\u00e0 di allestimento. Le pareti della Sala Sinopoli sono rivestite di pannelli in legno di ciliegio americano mentre le gallerie sono realizzate con il classico mattoncino sabbiato. Ideale per assemblee e convention aziendali, con e senza momenti di spettacolo.<\/p>\n","protected":false},"excerpt":{"rendered":"Dedicata al grande compositore e direttore d&#8217;orchestra Giuseppe Sinopoli, la Sala Sinopoli dell\u2019Auditorium ha una configurazione modulabile e garantisce allo spettatore una visibilit\u00e0 e una qualit\u00e0 del suono ottimali. Caratterizzata da una grande flessibilit\u00e0 distributiva e dimensioni adattabili, consente differenti possibilit\u00e0 di allestimento. Le pareti della Sala Sinopoli sono rivestite di pannelli in legno di [&hellip;]","protected":false},"featured_media":1073,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"class_list":["post-528","sala","type-sala","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sala Sinopoli | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/sala\/sala-sinopoli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sala Sinopoli | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Dedicata al grande compositore e direttore d&#8217;orchestra Giuseppe Sinopoli, la Sala Sinopoli dell\u2019Auditorium ha una configurazione modulabile e garantisce allo spettatore una visibilit\u00e0 e una qualit\u00e0 del suono ottimali. Caratterizzata da una grande flessibilit\u00e0 distributiva e dimensioni adattabili, consente differenti possibilit\u00e0 di allestimento. Le pareti della Sala Sinopoli sono rivestite di pannelli in legno di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/sala\/sala-sinopoli\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-10T08:19:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/sala-sinopoli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1517\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/sala\\\/sala-sinopoli\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/sala\\\/sala-sinopoli\\\/\",\"name\":\"Sala Sinopoli | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/sala\\\/sala-sinopoli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/sala\\\/sala-sinopoli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/sala-sinopoli.jpg\",\"datePublished\":\"2022-12-14T10:51:38+00:00\",\"dateModified\":\"2025-10-10T08:19:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/sala\\\/sala-sinopoli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/sala\\\/sala-sinopoli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/sala\\\/sala-sinopoli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/sala-sinopoli.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/sala-sinopoli.jpg\",\"width\":1517,\"height\":850,\"caption\":\"Sala Sinopoli\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/sala\\\/sala-sinopoli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sale\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/sala\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sala Sinopoli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sala Sinopoli | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/sala\/sala-sinopoli\/","og_locale":"it_IT","og_type":"article","og_title":"Sala Sinopoli | Auditorium Parco della Musica Ennio Morricone","og_description":"Dedicata al grande compositore e direttore d&#8217;orchestra Giuseppe Sinopoli, la Sala Sinopoli dell\u2019Auditorium ha una configurazione modulabile e garantisce allo spettatore una visibilit\u00e0 e una qualit\u00e0 del suono ottimali. Caratterizzata da una grande flessibilit\u00e0 distributiva e dimensioni adattabili, consente differenti possibilit\u00e0 di allestimento. Le pareti della Sala Sinopoli sono rivestite di pannelli in legno di [&hellip;]","og_url":"https:\/\/www.auditorium.com\/it\/sala\/sala-sinopoli\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2025-10-10T08:19:10+00:00","og_image":[{"width":1517,"height":850,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/sala-sinopoli.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/sala\/sala-sinopoli\/","url":"https:\/\/www.auditorium.com\/it\/sala\/sala-sinopoli\/","name":"Sala Sinopoli | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/sala\/sala-sinopoli\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/sala\/sala-sinopoli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/sala-sinopoli.jpg","datePublished":"2022-12-14T10:51:38+00:00","dateModified":"2025-10-10T08:19:10+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/sala\/sala-sinopoli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/sala\/sala-sinopoli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/sala\/sala-sinopoli\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/sala-sinopoli.jpg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/sala-sinopoli.jpg","width":1517,"height":850,"caption":"Sala Sinopoli"},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/sala\/sala-sinopoli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Sale","item":"https:\/\/www.auditorium.com\/it\/sala\/"},{"@type":"ListItem","position":3,"name":"Sala Sinopoli"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/sala\/528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/sala"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/sala"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/1073"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}