{"id":11358,"date":"2023-11-14T12:20:37","date_gmt":"2023-11-14T11:20:37","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=rassegne&#038;p=11358"},"modified":"2024-04-08T11:43:45","modified_gmt":"2024-04-08T10:43:45","slug":"lezioni-di-rock-le-scoperte-dellamerica","status":"publish","type":"rassegne","link":"https:\/\/www.auditorium.com\/it\/rassegne\/lezioni-di-rock-le-scoperte-dellamerica\/","title":{"rendered":"Lezioni di Rock &#8211; Le scoperte dell&#8217;America"},"content":{"rendered":"<p><strong>LA RASSEGNA \u00c8\u00a0ANNULLATA<\/strong><\/p>\n<p>Per gli acquirenti dei singoli biglietti delle lezioni, \u00e8 previsto il rimborso monetario nelle seguenti modalit\u00e0:<\/p>\n<ul>\n<li>Gli spettatori che hanno acquistato il biglietto sul sito <a href=\"http:\/\/ticketone.it\/\">TicketOne.it<\/a>e tramite Call Center riceveranno il riaccredito in automatico sullo stesso strumento di pagamento utilizzato in fase di acquisto, senza la necessit\u00e0 di procedere ad alcuna richiesta di rimborso;<\/li>\n<li>Gli spettatori che hanno acquistato il biglietto presso uno dei Punti Vendita TicketOne dovranno fare richiesta di rimborso entro e non oltre il 15 aprile 2024, secondo le procedure riportate alla pagina\u00a0<a href=\"http:\/\/www.rimborso.info\/\">www.rimborso.info<\/a><\/li>\n<li>Gli spettatori che hanno acquistato il biglietto presso la biglietteria dell\u2019Auditorium Parco della Musica dovranno presentarsi allo stesso botteghino muniti del biglietto per ottenerne il rimborso, entro e non oltre il 15 aprile 2024.<\/li>\n<\/ul>\n<p>Per chi ha sottoscritto l\u2019abbonamento all\u2019intera rassegna di \u2018\u2019Lezioni di Rock\u2019\u2019: seguiranno informazioni sulla modalit\u00e0 di rimborso della quota parte dell\u2019abbonamento non goduta. Per informazioni<a href=\"mailto:abbonati@musicaperroma.it\">abbonati@musicaperroma.it<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"Quattro lezioni per provare a raccontare l&#8217;America.\u00a0Con Gino Castaldo, Ernesto Assante e la band capitanata da Gigi De Rienzo.","protected":false},"featured_media":11508,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[52],"gruppo_edizione":[],"class_list":["post-11358","rassegne","type-rassegne","status-publish","has-post-thumbnail","hentry","event_categories-lezioni"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lezioni di Rock - Le scoperte dell&#039;America | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"description\" content=\"Quattro lezioni per provare a raccontare l&#039;America.\u00a0Con Gino Castaldo, Ernesto Assante e la band capitanata da Gigi De Rienzo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/rassegne\/lezioni-di-rock-le-scoperte-dellamerica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lezioni di Rock - Le scoperte dell&#039;America | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Quattro lezioni per provare a raccontare l&#039;America.\u00a0Con Gino Castaldo, Ernesto Assante e la band capitanata da Gigi De Rienzo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/rassegne\/lezioni-di-rock-le-scoperte-dellamerica\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-08T10:43:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/11\/1920x1080-america.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/rassegne\\\/lezioni-di-rock-le-scoperte-dellamerica\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/rassegne\\\/lezioni-di-rock-le-scoperte-dellamerica\\\/\",\"name\":\"Lezioni di Rock - Le scoperte dell'America | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/rassegne\\\/lezioni-di-rock-le-scoperte-dellamerica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/rassegne\\\/lezioni-di-rock-le-scoperte-dellamerica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/1920x1080-america.jpg\",\"datePublished\":\"2023-11-14T11:20:37+00:00\",\"dateModified\":\"2024-04-08T10:43:45+00:00\",\"description\":\"Quattro lezioni per provare a raccontare l'America.\u00a0Con Gino Castaldo, Ernesto Assante e la band capitanata da Gigi De Rienzo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/rassegne\\\/lezioni-di-rock-le-scoperte-dellamerica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/rassegne\\\/lezioni-di-rock-le-scoperte-dellamerica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/rassegne\\\/lezioni-di-rock-le-scoperte-dellamerica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/1920x1080-america.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/1920x1080-america.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/rassegne\\\/lezioni-di-rock-le-scoperte-dellamerica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rassegne\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/rassegne\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lezioni di Rock &#8211; Le scoperte dell&#8217;America\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lezioni di Rock - Le scoperte dell'America | Auditorium Parco della Musica Ennio Morricone","description":"Quattro lezioni per provare a raccontare l'America.\u00a0Con Gino Castaldo, Ernesto Assante e la band capitanata da Gigi De Rienzo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/rassegne\/lezioni-di-rock-le-scoperte-dellamerica\/","og_locale":"it_IT","og_type":"article","og_title":"Lezioni di Rock - Le scoperte dell'America | Auditorium Parco della Musica Ennio Morricone","og_description":"Quattro lezioni per provare a raccontare l'America.\u00a0Con Gino Castaldo, Ernesto Assante e la band capitanata da Gigi De Rienzo.","og_url":"https:\/\/www.auditorium.com\/it\/rassegne\/lezioni-di-rock-le-scoperte-dellamerica\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2024-04-08T10:43:45+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/11\/1920x1080-america.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/rassegne\/lezioni-di-rock-le-scoperte-dellamerica\/","url":"https:\/\/www.auditorium.com\/it\/rassegne\/lezioni-di-rock-le-scoperte-dellamerica\/","name":"Lezioni di Rock - Le scoperte dell'America | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/rassegne\/lezioni-di-rock-le-scoperte-dellamerica\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/rassegne\/lezioni-di-rock-le-scoperte-dellamerica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/11\/1920x1080-america.jpg","datePublished":"2023-11-14T11:20:37+00:00","dateModified":"2024-04-08T10:43:45+00:00","description":"Quattro lezioni per provare a raccontare l'America.\u00a0Con Gino Castaldo, Ernesto Assante e la band capitanata da Gigi De Rienzo.","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/rassegne\/lezioni-di-rock-le-scoperte-dellamerica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/rassegne\/lezioni-di-rock-le-scoperte-dellamerica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/rassegne\/lezioni-di-rock-le-scoperte-dellamerica\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/11\/1920x1080-america.jpg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/11\/1920x1080-america.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/rassegne\/lezioni-di-rock-le-scoperte-dellamerica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Rassegne","item":"https:\/\/www.auditorium.com\/it\/rassegne\/"},{"@type":"ListItem","position":3,"name":"Lezioni di Rock &#8211; Le scoperte dell&#8217;America"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/rassegne\/11358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/rassegne"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/rassegne"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/11508"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=11358"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=11358"},{"taxonomy":"gruppo_edizione","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/gruppo_edizione?post=11358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}