{"id":6648,"date":"2023-04-17T10:57:55","date_gmt":"2023-04-17T09:57:55","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=6648"},"modified":"2023-05-04T16:38:05","modified_gmt":"2023-05-04T15:38:05","slug":"1969-lanno-della-musica-libera","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/1969-lanno-della-musica-libera\/","title":{"rendered":"Speciale Lezioni di Rock 2023: 1969, l&#8217;anno della musica libera"},"content":{"rendered":"<div>\n<p style=\"text-align: center;\">Con <strong>Ernesto Assante<\/strong> e <strong>Gino Castaldo<\/strong> e<br \/>\n<strong>AuditoriumBand:<\/strong><br \/>\n<strong>Gigi De Rienzo<\/strong> \u2013 Basso e direzione<br \/>\n<strong>Franco Giacoia<\/strong> \u2013 Chitarra<br \/>\n<strong>Osvaldo Di Dio<\/strong> \u2013 Chitarra e voce<br \/>\n<strong>Claudio Romano<\/strong> \u2013 Batteria<br \/>\n<strong>Paolo Sessa<\/strong> \u2013 Tastiere<br \/>\n<strong>Paolo Ryo<\/strong> \u2013 Voce<\/p>\n<p class=\"s3\"><span class=\"bumpedfont15\">L\u2019idea di parlare e<\/span><span class=\"apple-converted-space\">\u00a0<\/span><span class=\"bumpedfont15\">\u201csuonare\u201d<\/span><span class=\"apple-converted-space\">\u00a0<\/span><span class=\"bumpedfont15\">del 1969 parte prima di tutto da una suggestione personale, quella di provare a condividere la sensazione avuta all\u2019epoca \u00e8 ancora viva dentro di noi, di essere travolti da una sequenza di fenomeni musicali forti e diversi, tutti portatori di un seme prezioso. Musica che sembrava essere in grado di cambiare chi l\u2019ascoltava, permettendo nuove visioni, nuove idee e nuovi sentimenti. Musica che ha certamente cambiato noi. quasi un racconto di formazione, dunque, che continua ben oltre la generazione che l\u2019ha vissuto in prima persona.<\/span><\/p>\n<\/div>\n<div>\n<p class=\"s3\"><span class=\"bumpedfont15\">Il 1969<\/span><span class=\"apple-converted-space\">\u00a0<\/span><span class=\"bumpedfont15\">\u00e8<\/span><span class=\"apple-converted-space\">\u00a0<\/span><span class=\"bumpedfont15\">pieno di nuovi inizi, <strong>King Crimson<\/strong>,<strong> Led Zeppelin<\/strong>,<strong> Iggy Pop<\/strong>, \u00e8 l\u2019anno dei primi grandi successi dei <strong>Jackson 5<\/strong> e di <strong>David Bowie<\/strong>, della prima volta di <strong>Battisti<\/strong> come cantante a Sanremo, di riconferme come per i <strong>Rolling Stones<\/strong> o i <strong>Creedence<\/strong>,<\/span><span class=\"apple-converted-space\">\u00a0<\/span><span class=\"bumpedfont15\">\u00e8<\/span><span class=\"apple-converted-space\">\u00a0<\/span><span class=\"bumpedfont15\">l\u2019anno del clamoroso addio dei <strong>Beatles<\/strong>, della svolta elettrica di<strong> Miles Davis<\/strong>, e poi di Woodstock, che grazie al cinema moltiplica all\u2019infinito un pubblico gi\u00e0<\/span><span class=\"apple-converted-space\">\u00a0<\/span><span class=\"bumpedfont15\">oceanico e racconta al resto del mondo dove<\/span><span class=\"apple-converted-space\">\u00a0<\/span><span class=\"bumpedfont15\">\u00e8<\/span><span class=\"apple-converted-space\">\u00a0<\/span><span class=\"bumpedfont15\">arrivato il rock.<\/span><\/p>\n<\/div>\n<div>\n<p class=\"s3\"><span class=\"apple-converted-space\">Proporremo dal vivo alcuni dei brani chiave di quell\u2019anno, internazionali e italiani, rock, jazz, canzone, accompagnando i suoni con le parole del racconto di un\u2019epoca.\u00a0<\/span><span class=\"bumpedfont15\">Suonare la musica del 1969<\/span><span class=\"apple-converted-space\">\u00a0<\/span><span class=\"bumpedfont15\">\u00e8<\/span><span class=\"apple-converted-space\">\u00a0<\/span><span class=\"bumpedfont15\">ripercorrere un tratto della rivoluzione di quegli anni, quando la rivoluzione era<\/span><span class=\"apple-converted-space\">\u00a0<\/span><span class=\"bumpedfont15\">possibile. Ed \u00e8 un modo per dimostrare che la musica \u00e8 ancora terribilmente attuale<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"Proporremo dal vivo alcuni dei brani chiave del 1969, internazionali e italiani, rock, jazz, canzone, accompagnando i suoni con le parole del racconto di un\u2019epoca.","protected":false},"featured_media":6928,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[85],"event_genre":[],"event_themes":[],"event_format":[73],"event_consigliati":[],"class_list":["post-6648","event","type-event","status-publish","has-post-thumbnail","hentry","event_categories-pop-rock","event_format-lezioni"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Speciale Lezioni di Rock 2023: 1969, l&#039;anno della musica libera | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"description\" content=\"Proporremo dal vivo alcuni dei brani chiave del 1969, internazionali e italiani, rock, jazz, canzone, accompagnando i suoni con le parole del racconto di un\u2019epoca.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/1969-lanno-della-musica-libera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Speciale Lezioni di Rock 2023: 1969, l&#039;anno della musica libera | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Proporremo dal vivo alcuni dei brani chiave del 1969, internazionali e italiani, rock, jazz, canzone, accompagnando i suoni con le parole del racconto di un\u2019epoca.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/1969-lanno-della-musica-libera\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-04T15:38:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/04\/people-g2fb3e093d_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/1969-lanno-della-musica-libera\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/1969-lanno-della-musica-libera\\\/\",\"name\":\"Speciale Lezioni di Rock 2023: 1969, l'anno della musica libera | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/1969-lanno-della-musica-libera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/1969-lanno-della-musica-libera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/people-g2fb3e093d_1920.jpg\",\"datePublished\":\"2023-04-17T09:57:55+00:00\",\"dateModified\":\"2023-05-04T15:38:05+00:00\",\"description\":\"Proporremo dal vivo alcuni dei brani chiave del 1969, internazionali e italiani, rock, jazz, canzone, accompagnando i suoni con le parole del racconto di un\u2019epoca.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/1969-lanno-della-musica-libera\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/1969-lanno-della-musica-libera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/1969-lanno-della-musica-libera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/people-g2fb3e093d_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/people-g2fb3e093d_1920.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/1969-lanno-della-musica-libera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Speciale Lezioni di Rock 2023: 1969, l&#8217;anno della musica libera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Speciale Lezioni di Rock 2023: 1969, l'anno della musica libera | Auditorium Parco della Musica Ennio Morricone","description":"Proporremo dal vivo alcuni dei brani chiave del 1969, internazionali e italiani, rock, jazz, canzone, accompagnando i suoni con le parole del racconto di un\u2019epoca.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/1969-lanno-della-musica-libera\/","og_locale":"it_IT","og_type":"article","og_title":"Speciale Lezioni di Rock 2023: 1969, l'anno della musica libera | Auditorium Parco della Musica Ennio Morricone","og_description":"Proporremo dal vivo alcuni dei brani chiave del 1969, internazionali e italiani, rock, jazz, canzone, accompagnando i suoni con le parole del racconto di un\u2019epoca.","og_url":"https:\/\/www.auditorium.com\/it\/event\/1969-lanno-della-musica-libera\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2023-05-04T15:38:05+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/04\/people-g2fb3e093d_1920.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/1969-lanno-della-musica-libera\/","url":"https:\/\/www.auditorium.com\/it\/event\/1969-lanno-della-musica-libera\/","name":"Speciale Lezioni di Rock 2023: 1969, l'anno della musica libera | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/1969-lanno-della-musica-libera\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/1969-lanno-della-musica-libera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/04\/people-g2fb3e093d_1920.jpg","datePublished":"2023-04-17T09:57:55+00:00","dateModified":"2023-05-04T15:38:05+00:00","description":"Proporremo dal vivo alcuni dei brani chiave del 1969, internazionali e italiani, rock, jazz, canzone, accompagnando i suoni con le parole del racconto di un\u2019epoca.","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/1969-lanno-della-musica-libera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/1969-lanno-della-musica-libera\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/1969-lanno-della-musica-libera\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/04\/people-g2fb3e093d_1920.jpg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/04\/people-g2fb3e093d_1920.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/1969-lanno-della-musica-libera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Speciale Lezioni di Rock 2023: 1969, l&#8217;anno della musica libera"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/6648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/6928"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=6648"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=6648"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=6648"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=6648"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=6648"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=6648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}