{"id":48998,"date":"2026-09-01T15:32:05","date_gmt":"2026-09-01T14:32:05","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=48998"},"modified":"2026-09-01T15:34:23","modified_gmt":"2026-09-01T14:34:23","slug":"nicola-piovani-17","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/nicola-piovani-17\/","title":{"rendered":"Nicola Piovani &#8211; &#8220;Viaggi di Ulisse&#8221;"},"content":{"rendered":"<p style=\"text-align: center;\"><em><strong>Viaggi di Ulisse<\/strong><strong>\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em>Concerto mitologico<\/em><\/p>\n<p style=\"text-align: center;\">Scritto e diretto da<strong> Nicola Piovani<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>\u00a0<\/strong><\/p>\n<p><em><strong>Viaggi di Ulisse<\/strong><\/em>\u00a0\u00e8 un racconto in musica, per strumenti che si concertano con voci registrate. I temi del racconto sono le emozioni che mi hanno lasciato le letture e l\u2019immaginazione di alcuni viaggi di Ulisse, personaggio vecchio di tre millenni, figura di un fascino e di una meraviglia ancora oggi indecifrabili. Con la musica strumentale, ovviamente, non raccontiamo i fatti che solo la parola pu\u00f2 descrivere. Ma la musica pu\u00f2 tentare di materializzare la commozione che quei fatti ancora oggi sono capaci di suscitare.<\/p>\n<p>L\u2019organico comprende il pianoforte, il contrabbasso, il sax, il violoncello, le percussioni, la tastiera elettronica; e voci registrate che recitano versi di poeti \u2013 <strong>James Joyce, Konstantinos Kavafis, Omero, Umberto Saba, Torquato Tasso<\/strong> \u2013 voci inserite nella partitura e che hanno un ruolo fondamentalmente sonoro.<\/p>\n<p><em>Il concerto mitologico &#8220;Viaggi di Ulisse&#8221;\u00a0punta a ricreare in teatro l\u2019incanto di quelle vicende odissiache che da sempre mi seducono; e spero di condividere quell\u2019incanto\u00a0innanzitutto\u00a0col pubblico.<\/em><\/p>\n<p><em>\u00a0\u00a0 \u00a0\u00a0\u00a0\u00a0 Nicola Piovani<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Scritto e diretto da <strong>Nicola Piovani<\/strong><\/p>\n<p>Solisti dell\u2019orchestra:<\/p>\n<p><strong>Marina Cesari<\/strong> sax \/ clarinetto<\/p>\n<p><strong>Sergio Colicchio<\/strong> tastiera \/ fisarmonica<\/p>\n<p><strong>Pasquale Filast\u00f2<\/strong> violoncello \/ mandoloncello<\/p>\n<p><strong>Marco Loddo<\/strong> contrabbasso<\/p>\n<p><strong>Vittorino Naso<\/strong> batteria \/ percussioni<\/p>\n<p><strong>Nicola Piovani<\/strong> pianoforte<\/p>\n<p>&nbsp;<\/p>\n<p>Attori in video: <strong>Carlo Cecchi, Paila Pavese, Massimo Popolizio, Mariano Rigillo, Virgilio Zernitz, Chiara Baffi, Massimo Wertmuller<\/strong><\/p>\n<p>Voci registrate: <strong>James Joyce, Siobhan McKenna<\/strong><\/p>\n<p>Testi: <strong>Konstantinos Kavafis, Omero, James Joyce, Torquato Tasso, Pindaro, Umberto Saba<\/strong><\/p>\n<p>Disegni: <strong>Milo Manara<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"Viaggi di Ulisse\u00a0 Concerto mitologico Scritto e diretto da Nicola Piovani \u00a0 Viaggi di Ulisse\u00a0\u00e8 un racconto in musica, per strumenti che si concertano con voci registrate. I temi del racconto sono le emozioni che mi hanno lasciato le letture e l\u2019immaginazione di alcuni viaggi di Ulisse, personaggio vecchio di tre millenni, figura di un [&hellip;]","protected":false},"featured_media":42680,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[],"event_genre":[61],"event_themes":[],"event_format":[],"event_consigliati":[],"class_list":["post-48998","event","type-event","status-publish","has-post-thumbnail","hentry","event_genre-contemporanea"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nicola Piovani - &quot;Viaggi di Ulisse&quot; | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/nicola-piovani-17\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nicola Piovani - &quot;Viaggi di Ulisse&quot; | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Viaggi di Ulisse\u00a0 Concerto mitologico Scritto e diretto da Nicola Piovani \u00a0 Viaggi di Ulisse\u00a0\u00e8 un racconto in musica, per strumenti che si concertano con voci registrate. I temi del racconto sono le emozioni che mi hanno lasciato le letture e l\u2019immaginazione di alcuni viaggi di Ulisse, personaggio vecchio di tre millenni, figura di un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/nicola-piovani-17\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T14:34:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/10\/PIOVANI_ULISSE_008-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/nicola-piovani-17\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/nicola-piovani-17\\\/\",\"name\":\"Nicola Piovani - \\\"Viaggi di Ulisse\\\" | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/nicola-piovani-17\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/nicola-piovani-17\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/PIOVANI_ULISSE_008-scaled.jpg\",\"datePublished\":\"2026-09-01T14:32:05+00:00\",\"dateModified\":\"2026-09-01T14:34:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/nicola-piovani-17\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/nicola-piovani-17\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/nicola-piovani-17\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/PIOVANI_ULISSE_008-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/PIOVANI_ULISSE_008-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Roma, Auditorium Parco della Musica 18 07 2021 NICOLA PIOVANI VIAGGI DI ULISSE \u00a9Fondazione Musica Per Roma - Foto Musacchio, Ianniello &amp; Pasqualini ******************* NB la presente foto puo' essere utilizzata esclusivamente per l'avvenimento in oggetto o per pubblicazioni riguardanti Fondazione Musica Per Roma\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/nicola-piovani-17\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nicola Piovani &#8211; &#8220;Viaggi di Ulisse&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nicola Piovani - \"Viaggi di Ulisse\" | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/nicola-piovani-17\/","og_locale":"it_IT","og_type":"article","og_title":"Nicola Piovani - \"Viaggi di Ulisse\" | Auditorium Parco della Musica Ennio Morricone","og_description":"Viaggi di Ulisse\u00a0 Concerto mitologico Scritto e diretto da Nicola Piovani \u00a0 Viaggi di Ulisse\u00a0\u00e8 un racconto in musica, per strumenti che si concertano con voci registrate. I temi del racconto sono le emozioni che mi hanno lasciato le letture e l\u2019immaginazione di alcuni viaggi di Ulisse, personaggio vecchio di tre millenni, figura di un [&hellip;]","og_url":"https:\/\/www.auditorium.com\/it\/event\/nicola-piovani-17\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2026-09-01T14:34:23+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/10\/PIOVANI_ULISSE_008-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/nicola-piovani-17\/","url":"https:\/\/www.auditorium.com\/it\/event\/nicola-piovani-17\/","name":"Nicola Piovani - \"Viaggi di Ulisse\" | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/nicola-piovani-17\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/nicola-piovani-17\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/10\/PIOVANI_ULISSE_008-scaled.jpg","datePublished":"2026-09-01T14:32:05+00:00","dateModified":"2026-09-01T14:34:23+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/nicola-piovani-17\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/nicola-piovani-17\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/nicola-piovani-17\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/10\/PIOVANI_ULISSE_008-scaled.jpg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/10\/PIOVANI_ULISSE_008-scaled.jpg","width":2560,"height":1707,"caption":"Roma, Auditorium Parco della Musica 18 07 2021 NICOLA PIOVANI VIAGGI DI ULISSE \u00a9Fondazione Musica Per Roma - Foto Musacchio, Ianniello &amp; Pasqualini ******************* NB la presente foto puo' essere utilizzata esclusivamente per l'avvenimento in oggetto o per pubblicazioni riguardanti Fondazione Musica Per Roma"},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/nicola-piovani-17\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Nicola Piovani &#8211; &#8220;Viaggi di Ulisse&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/48998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/42680"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=48998"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=48998"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=48998"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=48998"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=48998"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=48998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}