{"id":43678,"date":"2025-12-10T12:00:51","date_gmt":"2025-12-10T10:00:51","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=43678"},"modified":"2026-01-22T12:32:55","modified_gmt":"2026-01-22T11:32:55","slug":"frida-bollani-magoni","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/frida-bollani-magoni\/","title":{"rendered":"FRIDA LIVE"},"content":{"rendered":"<p style=\"font-weight: 400;\">Frida porta la sua musica in <strong>tour<\/strong> nelle principali citt\u00e0 italiane con uno <strong>spettacolo<\/strong> intenso, elegante e profondamente autentico. <strong>Cantante e pianista<\/strong>, Frida presenta al pubblico un concerto ricco di canzoni e suggestioni, in cui convivono grandi classici della musica italiana e internazionale insieme ai suoi brani originali, scritti e composti da lei. Ogni brano del repertorio racconta una parte del suo personale <strong>percorso musicale<\/strong>: dai primissimi ascolti, alle influenze pi\u00f9 recenti. Ne nasce una proposta artistica sfaccettata e contemporanea, che attraversa il pop, il jazz, la musica d\u2019autore, con richiami alla musica classica, arrangiamenti pi\u00f9 complessi e suggestioni elettroniche, impreziosite anche da effetti vocali. Il <strong>concerto<\/strong> diventa cos\u00ec un vero e proprio itinerario musicale, da\u00a0<em>You\u2019ve Got a Friend<\/em>\u00a0di Carole King \u2013 uno dei primi brani ascoltati da Frida da bambina \u2013 a\u00a0<em>Futura<\/em>\u00a0di Lucio Dalla, canzone senza tempo capace di attraversare le generazioni. Le diverse declinazioni dell\u2019amore trovano spazio in\u00a0<em>Back to Black<\/em>\u00a0di Amy Winehouse o in\u00a0<em>There You\u2019ll Be<\/em>\u00a0di Faith Hill, passando per le atmosfere poetiche di Battiato, Paolo Conte e Leonard Cohen, di cui Frida interpreta una intensa e toccante\u00a0<em>Hallelujah<\/em>, capace di emozionare profondamente il <strong>pubblico<\/strong>.<\/p>\n<p style=\"font-weight: 400;\">Lo spettacolo di Frida \u00e8 un caleidoscopio di colori musicali: non c\u2019\u00e8 un genere unico, ma un intreccio armonioso di linguaggi sonori. E cos\u00ec la sua <strong>voce<\/strong> \u2014 delicata ma potente, limpida, giovane e sincera \u2014 si muove con naturalezza tra diverse atmosfere, capace di salire verso le note pi\u00f9 alte e di restituire ogni brano con grande maturit\u00e0 espressiva. Sul palco, Frida \u00e8 affiancata dal musicista britannico Mark Glentworth. Insieme portano un <strong>sound<\/strong> <strong>ricco e contemporaneo<\/strong>, grazie all\u2019uso del pianoforte elettrico, del vibrafono e di altri strumenti elettrici ed effetti, che arricchiscono il suono, i colori e l\u2019impatto emotivo di ogni brano proposto.<\/p>\n<p style=\"font-weight: 400;\">Figlia d\u2019arte di <strong>Stefano Bollani e Petra Magoni<\/strong>, Frida \u00e8 cresciuta immersa nella musica, sviluppando fin da giovanissima una solida formazione e una sensibilit\u00e0 artistica personale. Ne emerge una personalit\u00e0 luminosa, fatta di lirismo e ironia, estro e fantasia, capace di coniugare tecnica, emozione e autenticit\u00e0.<\/p>\n<p style=\"font-weight: 400;\">Un concerto che \u00e8 molto pi\u00f9 di una semplice esibizione: \u00e8 un incontro, un racconto musicale e umano che lascia il segno. Negli anni Frida ha conquistato un pubblico vasto ed eterogeneo, salendo su numerosi palchi importanti e anche istituzionali, nonostante la sua giovane et\u00e0. Tra i momenti pi\u00f9 significativi figura l\u2019esibizione al\u00a0<em><strong>Quirinale<\/strong><\/em>\u00a0in apertura della Festa della Repubblica, davanti al <strong>Presidente della Repubblica Sergio Mattarella<\/strong>, dove ha interpretato l\u2019Inno nazionale e altri brani con grande intensit\u00e0 e partecipazione. Inoltre, Frida \u00e8 stata protagonista agli\u00a0<em>Internazionali d\u2019Italia<\/em>\u00a0di Roma, dove ha cantato l\u2019Inno di Mameli prima delle finali di singolare, in un contesto di sport e spettacolo.<\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"Frida porta la sua musica in tour nelle principali citt\u00e0 italiane con uno spettacolo intenso, elegante e profondamente autentico. Cantante e pianista, Frida presenta al pubblico un concerto ricco di canzoni e suggestioni, in cui convivono grandi classici della musica italiana e internazionale insieme ai suoi brani originali, scritti e composti da lei. Ogni brano [&hellip;]","protected":false},"featured_media":44104,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[],"event_genre":[63],"event_themes":[],"event_format":[],"event_consigliati":[],"class_list":["post-43678","event","type-event","status-publish","has-post-thumbnail","hentry","event_genre-autore"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FRIDA LIVE | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/frida-bollani-magoni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FRIDA LIVE | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Frida porta la sua musica in tour nelle principali citt\u00e0 italiane con uno spettacolo intenso, elegante e profondamente autentico. Cantante e pianista, Frida presenta al pubblico un concerto ricco di canzoni e suggestioni, in cui convivono grandi classici della musica italiana e internazionale insieme ai suoi brani originali, scritti e composti da lei. Ogni brano [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/frida-bollani-magoni\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-22T11:32:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/12\/IMG_4752_Ph.-Fabrizio-Castello-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/frida-bollani-magoni\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/frida-bollani-magoni\\\/\",\"name\":\"FRIDA LIVE | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/frida-bollani-magoni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/frida-bollani-magoni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/IMG_4752_Ph.-Fabrizio-Castello-scaled.jpg\",\"datePublished\":\"2025-12-10T10:00:51+00:00\",\"dateModified\":\"2026-01-22T11:32:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/frida-bollani-magoni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/frida-bollani-magoni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/frida-bollani-magoni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/IMG_4752_Ph.-Fabrizio-Castello-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/IMG_4752_Ph.-Fabrizio-Castello-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/frida-bollani-magoni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FRIDA LIVE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FRIDA LIVE | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/frida-bollani-magoni\/","og_locale":"it_IT","og_type":"article","og_title":"FRIDA LIVE | Auditorium Parco della Musica Ennio Morricone","og_description":"Frida porta la sua musica in tour nelle principali citt\u00e0 italiane con uno spettacolo intenso, elegante e profondamente autentico. Cantante e pianista, Frida presenta al pubblico un concerto ricco di canzoni e suggestioni, in cui convivono grandi classici della musica italiana e internazionale insieme ai suoi brani originali, scritti e composti da lei. Ogni brano [&hellip;]","og_url":"https:\/\/www.auditorium.com\/it\/event\/frida-bollani-magoni\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2026-01-22T11:32:55+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/12\/IMG_4752_Ph.-Fabrizio-Castello-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/frida-bollani-magoni\/","url":"https:\/\/www.auditorium.com\/it\/event\/frida-bollani-magoni\/","name":"FRIDA LIVE | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/frida-bollani-magoni\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/frida-bollani-magoni\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/12\/IMG_4752_Ph.-Fabrizio-Castello-scaled.jpg","datePublished":"2025-12-10T10:00:51+00:00","dateModified":"2026-01-22T11:32:55+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/frida-bollani-magoni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/frida-bollani-magoni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/frida-bollani-magoni\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/12\/IMG_4752_Ph.-Fabrizio-Castello-scaled.jpg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/12\/IMG_4752_Ph.-Fabrizio-Castello-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/frida-bollani-magoni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"FRIDA LIVE"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/43678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/44104"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=43678"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=43678"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=43678"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=43678"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=43678"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=43678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}