{"id":43583,"date":"2025-11-27T16:44:56","date_gmt":"2025-11-27T14:44:56","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=43583"},"modified":"2025-12-28T17:37:10","modified_gmt":"2025-12-28T16:37:10","slug":"workshop-gospel-experience-3","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/workshop-gospel-experience-3\/","title":{"rendered":"Workshop Gospel Experience"},"content":{"rendered":"<p style=\"font-weight: 400;\">Con Michelle Maya Taylor e Lolita Rowe.<br \/>\nIl laboratorio \u00e8 aperto a tutte e tutti (dai 18 anni in su), basta avere una giusta intonazione e una minima conoscenza dell\u2019Inglese: non \u00e8 infatti richiesta la lettura della notazione musicale e saranno ben accetti i Cori Gospel gi\u00e0 attivi.<br \/>\nAlla fine del laboratorio, per chi vorr\u00e0 partecipare, \u00e8 prevista una esibizione finale, il 28 dicembre, nell\u2019ambito del concerto di The Florida Inspiratonal Singers, un ensemble costituito unicamente dai migliori solisti gospel dell\u2019area della Florida Centrale. Il gruppo \u00e8 diretto dalla talentuosa e pluripremiata Nikkie Taylor, nome non sconosciuto al pubblico italiano per i suoi numerosi tour con la formazione dei Voices of Victory.<br \/>\nCon un background consolidato sia a livello di performance live che di partecipazione nella vita religiosa della loro comunit\u00e0, sono pronti a infiammare il pubblico italiano con il loro esperienza, il loro talento e la loro grande energia. Lo scorso anno i Florida Ispirational Singers hanno fatto cantare, ballare e commuovere il Teatro Nazionale di Milano, il Teatro Alfieri di Torino e l&#8217;Auditorium Parco della Musica di Roma con tre concerti memorabili e sold out.<\/p>\n<p style=\"font-weight: 400;\">26 DICEMBRE 2025<br \/>\nOre 11:00\/13.00 \u2013 incontro con l\u2019insegnante, formazione della corale e audizione per selezione soliste e solisti<br \/>\nOre 14:00 \/17:00 \u2013 Preparazione repertorio<\/p>\n<p style=\"font-weight: 400;\">27 DICEMBRE 2025<br \/>\nOre 10:00\/13:00 \u2013 Preparazione repertorio<br \/>\nOre 14:00\/17:00 \u2013 Preparazione repertorio<\/p>\n<p style=\"font-weight: 400;\">28 DICEMBRE 2025<br \/>\nOre 10:00\/13:00 \u2013 Preparazione repertorio<br \/>\nOre 14:00\/17:00 \u2013 Preparazione repertorio<br \/>\nOre 18.00 \u2013 intervento del Coro nel concerto di The Florida Inspirational Singers | Sala Sinopoli<\/p>\n<p style=\"font-weight: 400;\"><strong>Il termine ultimo per iscriversi al Workshop \u00e8 il 18 dicembre 2025, il costo \u00e8 di 120\u20ac per i singoli e di \u20ac90 per i gruppi (minimo 8 iscritti per \u2018gruppo\u2019).<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>Attenzione! Il Workshop \u00e8 aperto ai soli maggiorenni.<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>Per informazioni e iscrizioni scrivere a:\u00a0<a href=\"mailto:educational@musicaperroma.it\">educational@musicaperroma.it<\/a><\/strong><\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"Con Michelle Maya Taylor e Lolita Rowe. Il laboratorio \u00e8 aperto a tutte e tutti (dai 18 anni in su), basta avere una giusta intonazione e una minima conoscenza dell\u2019Inglese: non \u00e8 infatti richiesta la lettura della notazione musicale e saranno ben accetti i Cori Gospel gi\u00e0 attivi. Alla fine del laboratorio, per chi vorr\u00e0 [&hellip;]","protected":false},"featured_media":42599,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[86],"event_genre":[268],"event_themes":[],"event_format":[],"event_consigliati":[],"class_list":["post-43583","event","type-event","status-publish","has-post-thumbnail","hentry","event_categories-world","event_genre-gospel"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Workshop Gospel Experience | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/workshop-gospel-experience-3\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Workshop Gospel Experience | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Con Michelle Maya Taylor e Lolita Rowe. Il laboratorio \u00e8 aperto a tutte e tutti (dai 18 anni in su), basta avere una giusta intonazione e una minima conoscenza dell\u2019Inglese: non \u00e8 infatti richiesta la lettura della notazione musicale e saranno ben accetti i Cori Gospel gi\u00e0 attivi. Alla fine del laboratorio, per chi vorr\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/workshop-gospel-experience-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-28T16:37:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/10\/GOSPEL-SITO-700x394.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/workshop-gospel-experience-3\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/workshop-gospel-experience-3\\\/\",\"name\":\"Workshop Gospel Experience | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/workshop-gospel-experience-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/workshop-gospel-experience-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/GOSPEL-SITO.png\",\"datePublished\":\"2025-11-27T14:44:56+00:00\",\"dateModified\":\"2025-12-28T16:37:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/workshop-gospel-experience-3\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/workshop-gospel-experience-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/workshop-gospel-experience-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/GOSPEL-SITO.png\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/GOSPEL-SITO.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/workshop-gospel-experience-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Workshop Gospel Experience\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Workshop Gospel Experience | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/workshop-gospel-experience-3\/","og_locale":"it_IT","og_type":"article","og_title":"Workshop Gospel Experience | Auditorium Parco della Musica Ennio Morricone","og_description":"Con Michelle Maya Taylor e Lolita Rowe. Il laboratorio \u00e8 aperto a tutte e tutti (dai 18 anni in su), basta avere una giusta intonazione e una minima conoscenza dell\u2019Inglese: non \u00e8 infatti richiesta la lettura della notazione musicale e saranno ben accetti i Cori Gospel gi\u00e0 attivi. Alla fine del laboratorio, per chi vorr\u00e0 [&hellip;]","og_url":"https:\/\/www.auditorium.com\/it\/event\/workshop-gospel-experience-3\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2025-12-28T16:37:10+00:00","og_image":[{"width":700,"height":394,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/10\/GOSPEL-SITO-700x394.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/workshop-gospel-experience-3\/","url":"https:\/\/www.auditorium.com\/it\/event\/workshop-gospel-experience-3\/","name":"Workshop Gospel Experience | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/workshop-gospel-experience-3\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/workshop-gospel-experience-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/10\/GOSPEL-SITO.png","datePublished":"2025-11-27T14:44:56+00:00","dateModified":"2025-12-28T16:37:10+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/workshop-gospel-experience-3\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/workshop-gospel-experience-3\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/workshop-gospel-experience-3\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/10\/GOSPEL-SITO.png","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/10\/GOSPEL-SITO.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/workshop-gospel-experience-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Workshop Gospel Experience"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/43583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/42599"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=43583"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=43583"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=43583"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=43583"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=43583"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=43583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}