{"id":42691,"date":"2025-10-16T16:38:24","date_gmt":"2025-10-16T14:38:24","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=42691"},"modified":"2025-10-16T16:42:44","modified_gmt":"2025-10-16T14:42:44","slug":"primavera-unplugged-quartaedizione","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/primavera-unplugged-quartaedizione\/","title":{"rendered":"Primavera Unplugged"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Primavera Unplugged<\/strong><\/p>\n<p style=\"text-align: center;\">Quarta Edizione<\/p>\n<p>&nbsp;<\/p>\n<p>Torna <strong>Primavera Unplugged<\/strong>, giunto alla sua quarta edizione, l\u2019evento annuale che mette in luce il talento dei giovani cantautori e cantautrici della <strong>Arte2o Music Academy<\/strong>, eccellenza romana nella formazione musicale.<\/p>\n<p>Sul prestigioso palco dell\u2019Auditorium Parco della Musica Ennio Morricone, gli allievi selezionati si esibiranno con una raccolta di brani inediti, frutto di un percorso di crescita artistica e professionale portato avanti durante tutto l\u2019anno accademico, sotto la guida dei docenti dell\u2019Academy.<\/p>\n<p>La serata sar\u00e0 condotta da <strong>Chiara Cami<\/strong>, giovane cantautrice romana dallo stile ironico e comunicativo, che accompagner\u00e0 il pubblico tra musica, racconti e curiosit\u00e0 sulla vita dei nuovi protagonisti della scena musicale.<\/p>\n<p>Primavera Unplugged \u00e8 un\u2019occasione speciale per ascoltare da vicino le voci emergenti della musica d\u2019autore e scoprire il risultato di un lavoro intenso e appassionato.<\/p>\n","protected":false},"excerpt":{"rendered":"Primavera Unplugged Quarta Edizione &nbsp; Torna Primavera Unplugged, giunto alla sua quarta edizione, l\u2019evento annuale che mette in luce il talento dei giovani cantautori e cantautrici della Arte2o Music Academy, eccellenza romana nella formazione musicale. Sul prestigioso palco dell\u2019Auditorium Parco della Musica Ennio Morricone, gli allievi selezionati si esibiranno con una raccolta di brani inediti, [&hellip;]","protected":false},"featured_media":42689,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[4],"event_genre":[],"event_themes":[],"event_format":[],"event_consigliati":[],"class_list":["post-42691","event","type-event","status-publish","has-post-thumbnail","hentry","event_categories-musica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Primavera Unplugged | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/primavera-unplugged-quartaedizione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primavera Unplugged | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Primavera Unplugged Quarta Edizione &nbsp; Torna Primavera Unplugged, giunto alla sua quarta edizione, l\u2019evento annuale che mette in luce il talento dei giovani cantautori e cantautrici della Arte2o Music Academy, eccellenza romana nella formazione musicale. Sul prestigioso palco dell\u2019Auditorium Parco della Musica Ennio Morricone, gli allievi selezionati si esibiranno con una raccolta di brani inediti, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/primavera-unplugged-quartaedizione\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-16T14:42:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/10\/primavera-unplugged.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1277\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/primavera-unplugged-quartaedizione\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/primavera-unplugged-quartaedizione\\\/\",\"name\":\"Primavera Unplugged | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/primavera-unplugged-quartaedizione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/primavera-unplugged-quartaedizione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/primavera-unplugged.png\",\"datePublished\":\"2025-10-16T14:38:24+00:00\",\"dateModified\":\"2025-10-16T14:42:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/primavera-unplugged-quartaedizione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/primavera-unplugged-quartaedizione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/primavera-unplugged-quartaedizione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/primavera-unplugged.png\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/primavera-unplugged.png\",\"width\":1920,\"height\":1277},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/primavera-unplugged-quartaedizione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primavera Unplugged\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primavera Unplugged | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/primavera-unplugged-quartaedizione\/","og_locale":"it_IT","og_type":"article","og_title":"Primavera Unplugged | Auditorium Parco della Musica Ennio Morricone","og_description":"Primavera Unplugged Quarta Edizione &nbsp; Torna Primavera Unplugged, giunto alla sua quarta edizione, l\u2019evento annuale che mette in luce il talento dei giovani cantautori e cantautrici della Arte2o Music Academy, eccellenza romana nella formazione musicale. Sul prestigioso palco dell\u2019Auditorium Parco della Musica Ennio Morricone, gli allievi selezionati si esibiranno con una raccolta di brani inediti, [&hellip;]","og_url":"https:\/\/www.auditorium.com\/it\/event\/primavera-unplugged-quartaedizione\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2025-10-16T14:42:44+00:00","og_image":[{"width":1920,"height":1277,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/10\/primavera-unplugged.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/primavera-unplugged-quartaedizione\/","url":"https:\/\/www.auditorium.com\/it\/event\/primavera-unplugged-quartaedizione\/","name":"Primavera Unplugged | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/primavera-unplugged-quartaedizione\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/primavera-unplugged-quartaedizione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/10\/primavera-unplugged.png","datePublished":"2025-10-16T14:38:24+00:00","dateModified":"2025-10-16T14:42:44+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/primavera-unplugged-quartaedizione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/primavera-unplugged-quartaedizione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/primavera-unplugged-quartaedizione\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/10\/primavera-unplugged.png","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/10\/primavera-unplugged.png","width":1920,"height":1277},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/primavera-unplugged-quartaedizione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Primavera Unplugged"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/42691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/42689"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=42691"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=42691"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=42691"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=42691"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=42691"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=42691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}