{"id":41026,"date":"2025-06-09T15:00:52","date_gmt":"2025-06-09T13:00:52","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=41026"},"modified":"2025-06-13T12:17:44","modified_gmt":"2025-06-13T10:17:44","slug":"yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\/","title":{"rendered":"Yama e Niyama: viaggio attraverso i principi etici dello yoga con Francesca Rosati"},"content":{"rendered":"<p><em>Yama e Niyama: viaggio attraverso i principi etici dello yoga<\/em><br \/>\n<em>A cura di Yogis4Nature<\/em><\/p>\n<p>Non violenza, onest\u00e0, purezza, studio di s\u00e9, non attaccamento: sono solo alcuni dei pilastri etici su cui si fonda lo yoga, ma anche i valori alla base di <strong>Yogis4Nature<\/strong>, associazione di volontariato che promuove il benessere, la tutela dell&#8217;ambiente e l&#8217;unione tra le persone. Le insegnanti di Yogis4Nature guideranno un ciclo di 10 pratiche yoga per esplorare Yama e Niyama, le norme etiche dello yoga appunto e come metterle in pratica sul tappetino e fuori. Le lezioni avranno un taglio pratico e sono aperte a tutti i livelli. \u00c8 necessario venire muniti di tappetino proprio.<\/p>\n<p><strong>Dieci lezioni, della durata di 75\u2019 | Capienza 25 persone a lezione<\/strong><br \/>\n<strong>Orari: \u00a08:30-9:45 in settimana | 9:00-10:15 la domenica<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"Yama e Niyama: viaggio attraverso i principi etici dello yoga A cura di Yogis4Nature Non violenza, onest\u00e0, purezza, studio di s\u00e9, non attaccamento: sono solo alcuni dei pilastri etici su cui si fonda lo yoga, ma anche i valori alla base di Yogis4Nature, associazione di volontariato che promuove il benessere, la tutela dell&#8217;ambiente e l&#8217;unione [&hellip;]","protected":false},"featured_media":39339,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[52],"event_genre":[],"event_themes":[],"event_format":[73],"event_consigliati":[],"class_list":["post-41026","event","type-event","status-publish","has-post-thumbnail","hentry","event_categories-lezioni","event_format-lezioni"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Yama e Niyama: viaggio attraverso i principi etici dello yoga con Francesca Rosati | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yama e Niyama: viaggio attraverso i principi etici dello yoga con Francesca Rosati | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Yama e Niyama: viaggio attraverso i principi etici dello yoga A cura di Yogis4Nature Non violenza, onest\u00e0, purezza, studio di s\u00e9, non attaccamento: sono solo alcuni dei pilastri etici su cui si fonda lo yoga, ma anche i valori alla base di Yogis4Nature, associazione di volontariato che promuove il benessere, la tutela dell&#8217;ambiente e l&#8217;unione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-13T10:17:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/03\/de-Luca_Francesca-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\\\/\",\"name\":\"Yama e Niyama: viaggio attraverso i principi etici dello yoga con Francesca Rosati | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/de-Luca_Francesca-scaled.jpg\",\"datePublished\":\"2025-06-09T13:00:52+00:00\",\"dateModified\":\"2025-06-13T10:17:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/de-Luca_Francesca-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/de-Luca_Francesca-scaled.jpg\",\"width\":2560,\"height\":1708},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yama e Niyama: viaggio attraverso i principi etici dello yoga con Francesca Rosati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yama e Niyama: viaggio attraverso i principi etici dello yoga con Francesca Rosati | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\/","og_locale":"it_IT","og_type":"article","og_title":"Yama e Niyama: viaggio attraverso i principi etici dello yoga con Francesca Rosati | Auditorium Parco della Musica Ennio Morricone","og_description":"Yama e Niyama: viaggio attraverso i principi etici dello yoga A cura di Yogis4Nature Non violenza, onest\u00e0, purezza, studio di s\u00e9, non attaccamento: sono solo alcuni dei pilastri etici su cui si fonda lo yoga, ma anche i valori alla base di Yogis4Nature, associazione di volontariato che promuove il benessere, la tutela dell&#8217;ambiente e l&#8217;unione [&hellip;]","og_url":"https:\/\/www.auditorium.com\/it\/event\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2025-06-13T10:17:44+00:00","og_image":[{"width":2560,"height":1708,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/03\/de-Luca_Francesca-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\/","url":"https:\/\/www.auditorium.com\/it\/event\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\/","name":"Yama e Niyama: viaggio attraverso i principi etici dello yoga con Francesca Rosati | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/03\/de-Luca_Francesca-scaled.jpg","datePublished":"2025-06-09T13:00:52+00:00","dateModified":"2025-06-13T10:17:44+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/03\/de-Luca_Francesca-scaled.jpg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/03\/de-Luca_Francesca-scaled.jpg","width":2560,"height":1708},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/yama-e-niyama-viaggio-attraverso-i-principi-etici-dello-yoga-8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Yama e Niyama: viaggio attraverso i principi etici dello yoga con Francesca Rosati"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/41026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/39339"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=41026"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=41026"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=41026"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=41026"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=41026"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=41026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}