{"id":38804,"date":"2025-03-20T11:52:01","date_gmt":"2025-03-20T10:52:01","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=38804"},"modified":"2025-04-01T10:47:45","modified_gmt":"2025-04-01T09:47:45","slug":"fra-terra-e-spazio-one-health","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/fra-terra-e-spazio-one-health\/","title":{"rendered":"Fra terra e spazio: one health"},"content":{"rendered":"<p style=\"font-weight: 400; text-align: center;\">A cura di <strong>CNR<\/strong>, <strong>ENEA<\/strong>, <strong>INAF<\/strong>,<\/p>\n<p style=\"font-weight: 400; text-align: center;\"><a href=\"https:\/\/www.auditorium.com\/it\/artist\/stefano-amalfitano\/\"><strong>Stefano Amalfitano<\/strong><\/a> Ricercatore dell\u2019Istituto di Ricerca sulle Acque del CNR<\/p>\n<p style=\"font-weight: 400; text-align: center;\"><a href=\"https:\/\/www.auditorium.com\/it\/artist\/annamaria-bevivino\/\"><strong>Annamaria Bevivino <\/strong><\/a>Dirigente di ricerca del Dipartimento Sostenibilit\u00e0, ENEA<\/p>\n<p style=\"font-weight: 400; text-align: center;\"><a href=\"https:\/\/www.auditorium.com\/it\/artist\/patrizia-caraveo\/\"><strong>Patrizia Caraveo<\/strong><\/a> Dirigente di Ricerca all\u2019INAF<\/p>\n<p style=\"font-weight: 400; text-align: center;\">Modera <strong><a href=\"http:\/\/Luca Nardi\">Luca Nardi<\/a> <\/strong>Astrofisico e divulgatore scientifico<\/p>\n<p style=\"font-weight: 400; text-align: center;\">Letture <a href=\"http:\/\/Carla Costigliola\"><strong>Carla Costigliola<\/strong><\/a> Tecnologo in staff alla Direzione Generale dell\u2019ENEA<\/p>\n<p style=\"font-weight: 400;\">One Health, ovvero la salute vista come connessione tra esseri umani, animali e ambiente. La rete che connette diverse forme di vita \u00e8 composta da microorganismi che, con la loro straordinaria variet\u00e0, svolgono un ruolo essenziale nel mantenimento degli ecosistemi e della biodiversit\u00e0 terrestre. Ma nuove frontiere nella comprensione della salute globale si aprono alla ricerca, se consideriamo che forme di vita infinitamente piccole possono arrivare anche dallo spazio. Come ha detto il saggista americano, Stewart Brand: \u00abSe non ti piacciono i batteri, sei sul pianeta sbagliato\u00bb.<\/p>\n<p><i>Il biglietto \u00e8 valido per l\u2019ingresso, con fila prioritaria, entro e non oltre 10 minuti prima dall\u2019orario di inizio dell\u2019evento.<br \/>\n<\/i><i>Trascorso tale termine il biglietto perde la sua validit\u00e0, e priorit\u00e0 in ingresso viene data a chi sia eventualmente in fila d\u2019attesa<\/i><\/p>\n","protected":false},"excerpt":{"rendered":"A cura di CNR, ENEA, INAF, Stefano Amalfitano Ricercatore dell\u2019Istituto di Ricerca sulle Acque del CNR Annamaria Bevivino Dirigente di ricerca del Dipartimento Sostenibilit\u00e0, ENEA Patrizia Caraveo Dirigente di Ricerca all\u2019INAF Modera Luca Nardi Astrofisico e divulgatore scientifico Letture Carla Costigliola Tecnologo in staff alla Direzione Generale dell\u2019ENEA One Health, ovvero la salute vista come [&hellip;]","protected":false},"featured_media":38805,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[],"event_genre":[],"event_themes":[],"event_format":[],"event_consigliati":[],"class_list":["post-38804","event","type-event","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fra terra e spazio: one health | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/fra-terra-e-spazio-one-health\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fra terra e spazio: one health | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"A cura di CNR, ENEA, INAF, Stefano Amalfitano Ricercatore dell\u2019Istituto di Ricerca sulle Acque del CNR Annamaria Bevivino Dirigente di ricerca del Dipartimento Sostenibilit\u00e0, ENEA Patrizia Caraveo Dirigente di Ricerca all\u2019INAF Modera Luca Nardi Astrofisico e divulgatore scientifico Letture Carla Costigliola Tecnologo in staff alla Direzione Generale dell\u2019ENEA One Health, ovvero la salute vista come [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/fra-terra-e-spazio-one-health\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-01T09:47:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/03\/Fra-Terra-e-Spazio_-One-Health-2025-700x396.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"396\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/fra-terra-e-spazio-one-health\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/fra-terra-e-spazio-one-health\\\/\",\"name\":\"Fra terra e spazio: one health | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/fra-terra-e-spazio-one-health\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/fra-terra-e-spazio-one-health\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Fra-Terra-e-Spazio_-One-Health-2025.png\",\"datePublished\":\"2025-03-20T10:52:01+00:00\",\"dateModified\":\"2025-04-01T09:47:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/fra-terra-e-spazio-one-health\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/fra-terra-e-spazio-one-health\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/fra-terra-e-spazio-one-health\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Fra-Terra-e-Spazio_-One-Health-2025.png\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Fra-Terra-e-Spazio_-One-Health-2025.png\",\"width\":1840,\"height\":1040},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/fra-terra-e-spazio-one-health\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fra terra e spazio: one health\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fra terra e spazio: one health | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/fra-terra-e-spazio-one-health\/","og_locale":"it_IT","og_type":"article","og_title":"Fra terra e spazio: one health | Auditorium Parco della Musica Ennio Morricone","og_description":"A cura di CNR, ENEA, INAF, Stefano Amalfitano Ricercatore dell\u2019Istituto di Ricerca sulle Acque del CNR Annamaria Bevivino Dirigente di ricerca del Dipartimento Sostenibilit\u00e0, ENEA Patrizia Caraveo Dirigente di Ricerca all\u2019INAF Modera Luca Nardi Astrofisico e divulgatore scientifico Letture Carla Costigliola Tecnologo in staff alla Direzione Generale dell\u2019ENEA One Health, ovvero la salute vista come [&hellip;]","og_url":"https:\/\/www.auditorium.com\/it\/event\/fra-terra-e-spazio-one-health\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2025-04-01T09:47:45+00:00","og_image":[{"width":700,"height":396,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/03\/Fra-Terra-e-Spazio_-One-Health-2025-700x396.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/fra-terra-e-spazio-one-health\/","url":"https:\/\/www.auditorium.com\/it\/event\/fra-terra-e-spazio-one-health\/","name":"Fra terra e spazio: one health | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/fra-terra-e-spazio-one-health\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/fra-terra-e-spazio-one-health\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/03\/Fra-Terra-e-Spazio_-One-Health-2025.png","datePublished":"2025-03-20T10:52:01+00:00","dateModified":"2025-04-01T09:47:45+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/fra-terra-e-spazio-one-health\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/fra-terra-e-spazio-one-health\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/fra-terra-e-spazio-one-health\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/03\/Fra-Terra-e-Spazio_-One-Health-2025.png","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/03\/Fra-Terra-e-Spazio_-One-Health-2025.png","width":1840,"height":1040},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/fra-terra-e-spazio-one-health\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Fra terra e spazio: one health"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/38804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/38805"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=38804"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=38804"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=38804"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=38804"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=38804"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=38804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}