{"id":38700,"date":"2025-03-20T11:00:30","date_gmt":"2025-03-20T10:00:30","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=38700"},"modified":"2025-03-31T08:54:58","modified_gmt":"2025-03-31T07:54:58","slug":"dare-corpo-a-una-storia","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/dare-corpo-a-una-storia\/","title":{"rendered":"Dare corpo a una storia"},"content":{"rendered":"<p style=\"font-weight: 400; text-align: center;\">A cura di <strong>INAF<\/strong><\/p>\n<p style=\"font-weight: 400; text-align: center;\">Dialogo a due voci tra <a href=\"https:\/\/www.auditorium.com\/it\/artist\/valentina-guglielmo\/\"><strong>Valentina Guglielmo<\/strong><\/a> e <a href=\"https:\/\/www.auditorium.com\/it\/artist\/pablo-trincia\/\"><strong>Pablo Trincia<\/strong><\/a><\/p>\n<p style=\"font-weight: 400; text-align: center;\">Modera <a href=\"https:\/\/www.auditorium.com\/it\/artist\/davide-coero-borga\/\"><strong>Davide Coero Borga<\/strong><\/a><\/p>\n<p style=\"font-weight: 400;\">A partire dal primo podcast realizzato dall&#8217;INAF <em>Houston: cosa potrebbe andare storto?<\/em>, esploreremo come si costruisce una storia, con un&#8217;attenzione particolare al linguaggio e alle tecniche per declinarla come podcast. Con una guida d&#8217;eccezione: Pablo Trincia, che ne parler\u00e0 con Valentina Guglielmo, ideatrice di <em>Houston<\/em>, che lo ha anche realizzato. Dall&#8217;idea alla nascita: come un corpo una storia attraversa una fase ideativa per poi prendere vita, dall&#8217;ispirazione iniziale alla realizzazione finale. Un viaggio alla scoperta delle fasi che rendono un racconto scientifico coinvolgente, efficace e capace di dialogare con il pubblico.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\"><em>Il biglietto \u00e8 valido per l\u2019ingresso, con fila prioritaria,\u00a0entro e non oltre 10 minuti prima dall\u2019orario di inizio dell\u2019evento.<br \/>\nTrascorso tale termine il biglietto perde la sua validit\u00e0, e priorit\u00e0 in ingresso viene data a chi sia eventualmente in fila d\u2019attesa<\/em><\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"A cura di INAF Dialogo a due voci tra Valentina Guglielmo e Pablo Trincia Modera Davide Coero Borga A partire dal primo podcast realizzato dall&#8217;INAF Houston: cosa potrebbe andare storto?, esploreremo come si costruisce una storia, con un&#8217;attenzione particolare al linguaggio e alle tecniche per declinarla come podcast. Con una guida d&#8217;eccezione: Pablo Trincia, che [&hellip;]","protected":false},"featured_media":38701,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[],"event_genre":[],"event_themes":[],"event_format":[],"event_consigliati":[],"class_list":["post-38700","event","type-event","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dare corpo a una storia | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/dare-corpo-a-una-storia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dare corpo a una storia | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"A cura di INAF Dialogo a due voci tra Valentina Guglielmo e Pablo Trincia Modera Davide Coero Borga A partire dal primo podcast realizzato dall&#8217;INAF Houston: cosa potrebbe andare storto?, esploreremo come si costruisce una storia, con un&#8217;attenzione particolare al linguaggio e alle tecniche per declinarla come podcast. Con una guida d&#8217;eccezione: Pablo Trincia, che [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/dare-corpo-a-una-storia\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-31T07:54:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/03\/dare-corpo-e1742219107971.png\" \/>\n\t<meta property=\"og:image:width\" content=\"4500\" \/>\n\t<meta property=\"og:image:height\" content=\"2408\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/dare-corpo-a-una-storia\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/dare-corpo-a-una-storia\\\/\",\"name\":\"Dare corpo a una storia | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/dare-corpo-a-una-storia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/dare-corpo-a-una-storia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/dare-corpo-e1742219107971.png\",\"datePublished\":\"2025-03-20T10:00:30+00:00\",\"dateModified\":\"2025-03-31T07:54:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/dare-corpo-a-una-storia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/dare-corpo-a-una-storia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/dare-corpo-a-una-storia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/dare-corpo-e1742219107971.png\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/dare-corpo-e1742219107971.png\",\"width\":4500,\"height\":2408},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/dare-corpo-a-una-storia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dare corpo a una storia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dare corpo a una storia | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/dare-corpo-a-una-storia\/","og_locale":"it_IT","og_type":"article","og_title":"Dare corpo a una storia | Auditorium Parco della Musica Ennio Morricone","og_description":"A cura di INAF Dialogo a due voci tra Valentina Guglielmo e Pablo Trincia Modera Davide Coero Borga A partire dal primo podcast realizzato dall&#8217;INAF Houston: cosa potrebbe andare storto?, esploreremo come si costruisce una storia, con un&#8217;attenzione particolare al linguaggio e alle tecniche per declinarla come podcast. Con una guida d&#8217;eccezione: Pablo Trincia, che [&hellip;]","og_url":"https:\/\/www.auditorium.com\/it\/event\/dare-corpo-a-una-storia\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2025-03-31T07:54:58+00:00","og_image":[{"width":4500,"height":2408,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/03\/dare-corpo-e1742219107971.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/dare-corpo-a-una-storia\/","url":"https:\/\/www.auditorium.com\/it\/event\/dare-corpo-a-una-storia\/","name":"Dare corpo a una storia | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/dare-corpo-a-una-storia\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/dare-corpo-a-una-storia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/03\/dare-corpo-e1742219107971.png","datePublished":"2025-03-20T10:00:30+00:00","dateModified":"2025-03-31T07:54:58+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/dare-corpo-a-una-storia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/dare-corpo-a-una-storia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/dare-corpo-a-una-storia\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/03\/dare-corpo-e1742219107971.png","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/03\/dare-corpo-e1742219107971.png","width":4500,"height":2408},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/dare-corpo-a-una-storia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Dare corpo a una storia"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/38700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/38701"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=38700"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=38700"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=38700"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=38700"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=38700"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=38700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}