{"id":37778,"date":"2025-02-10T11:07:17","date_gmt":"2025-02-10T10:07:17","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=37778"},"modified":"2025-02-10T11:07:17","modified_gmt":"2025-02-10T10:07:17","slug":"pippo-pollina-2","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/pippo-pollina-2\/","title":{"rendered":"Pippo Pollina"},"content":{"rendered":"<p style=\"font-weight: 400;\"><strong>PIPPO POLLINA, La vita \u00e8 bella cosi com\u2019\u00e8. <\/strong><strong>Canzoni con quartetto cameristico<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400; text-align: center;\">Pippo Pollina\u00a0\u00a0voce e chitarra<\/p>\n<p style=\"font-weight: 400; text-align: center;\">Cecile Gr\u00fcebler violoncello<\/p>\n<p style=\"font-weight: 400; text-align: center;\">Roberto Petroli clarinetto e sassofoni<\/p>\n<p style=\"font-weight: 400; text-align: center;\">Elisa Sandrine pianoforte accordano e voce<\/p>\n<p style=\"font-weight: 400; text-align: center;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\">Eclettico musicista siciliano, da sempre riferimento obbligato nell\u2019Europa centrale della nostra canzone d\u2019autore pi\u00f9 nobile, Pippo Pollina rinnova di continuo il suo repertorio grazie a una fervida ispirazione che, sorretta da una forte tensione civile, si \u00e8 concretizzata nella realizzazione di 26 album e nella produzione di spettacoli di grande bellezza, segnati da una cura meticolosa, attenta anche ai dettagli.<\/p>\n<p style=\"font-weight: 400;\">Quest\u2019anno si propone in tour con una rinnovata formazione cameristica, che conferisce al suo canzoniere un tocco di eleganza e virtuosismo. Accompagnato dalla pianista e fisarmonicista Elisa Sandrini, dalla violoncellista Cecile Gr\u00fcebler e dal clarinettista e sassofonista Roberto Petroli, ripercorre cos\u00ec il suo vastissimo repertorio miscelando sapientemente classici e nuove composizioni. E regalando al suo<\/p>\n<p style=\"font-weight: 400;\">pubblico, dal nord Europa al sud dell\u2019Italia, emozioni e riflessioni sul mondo d\u2019oggi, cos\u00ec tormentato e pieno di\u00a0contraddizioni, eppure ricolmo ancora di stimolanti avventure che ci portano a guardare al futuro con ottimismo.<\/p>\n","protected":false},"excerpt":{"rendered":"PIPPO POLLINA, La vita \u00e8 bella cosi com\u2019\u00e8. Canzoni con quartetto cameristico &nbsp; Pippo Pollina\u00a0\u00a0voce e chitarra Cecile Gr\u00fcebler violoncello Roberto Petroli clarinetto e sassofoni Elisa Sandrine pianoforte accordano e voce \u00a0 Eclettico musicista siciliano, da sempre riferimento obbligato nell\u2019Europa centrale della nostra canzone d\u2019autore pi\u00f9 nobile, Pippo Pollina rinnova di continuo il suo repertorio [&hellip;]","protected":false},"featured_media":37781,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[],"event_genre":[63],"event_themes":[],"event_format":[],"event_consigliati":[],"class_list":["post-37778","event","type-event","status-publish","has-post-thumbnail","hentry","event_genre-autore"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pippo Pollina | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/pippo-pollina-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pippo Pollina | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"PIPPO POLLINA, La vita \u00e8 bella cosi com\u2019\u00e8. Canzoni con quartetto cameristico &nbsp; Pippo Pollina\u00a0\u00a0voce e chitarra Cecile Gr\u00fcebler violoncello Roberto Petroli clarinetto e sassofoni Elisa Sandrine pianoforte accordano e voce \u00a0 Eclettico musicista siciliano, da sempre riferimento obbligato nell\u2019Europa centrale della nostra canzone d\u2019autore pi\u00f9 nobile, Pippo Pollina rinnova di continuo il suo repertorio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/pippo-pollina-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/02\/Schermata-2025-01-21-alle-12.50.53.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/pippo-pollina-2\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/pippo-pollina-2\\\/\",\"name\":\"Pippo Pollina | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/pippo-pollina-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/pippo-pollina-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Schermata-2025-01-21-alle-12.50.53.png\",\"datePublished\":\"2025-02-10T10:07:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/pippo-pollina-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/pippo-pollina-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/pippo-pollina-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Schermata-2025-01-21-alle-12.50.53.png\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Schermata-2025-01-21-alle-12.50.53.png\",\"width\":1280,\"height\":708},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/pippo-pollina-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pippo Pollina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pippo Pollina | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/pippo-pollina-2\/","og_locale":"it_IT","og_type":"article","og_title":"Pippo Pollina | Auditorium Parco della Musica Ennio Morricone","og_description":"PIPPO POLLINA, La vita \u00e8 bella cosi com\u2019\u00e8. Canzoni con quartetto cameristico &nbsp; Pippo Pollina\u00a0\u00a0voce e chitarra Cecile Gr\u00fcebler violoncello Roberto Petroli clarinetto e sassofoni Elisa Sandrine pianoforte accordano e voce \u00a0 Eclettico musicista siciliano, da sempre riferimento obbligato nell\u2019Europa centrale della nostra canzone d\u2019autore pi\u00f9 nobile, Pippo Pollina rinnova di continuo il suo repertorio [&hellip;]","og_url":"https:\/\/www.auditorium.com\/it\/event\/pippo-pollina-2\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","og_image":[{"width":1280,"height":708,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/02\/Schermata-2025-01-21-alle-12.50.53.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/pippo-pollina-2\/","url":"https:\/\/www.auditorium.com\/it\/event\/pippo-pollina-2\/","name":"Pippo Pollina | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/pippo-pollina-2\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/pippo-pollina-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/02\/Schermata-2025-01-21-alle-12.50.53.png","datePublished":"2025-02-10T10:07:17+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/pippo-pollina-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/pippo-pollina-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/pippo-pollina-2\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/02\/Schermata-2025-01-21-alle-12.50.53.png","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2025\/02\/Schermata-2025-01-21-alle-12.50.53.png","width":1280,"height":708},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/pippo-pollina-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Pippo Pollina"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/37778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/37781"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=37778"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=37778"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=37778"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=37778"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=37778"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=37778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}