{"id":36284,"date":"2024-11-13T16:10:28","date_gmt":"2024-11-13T15:10:28","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=36284"},"modified":"2024-12-18T20:59:35","modified_gmt":"2024-12-18T19:59:35","slug":"riccardino-iii-15","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/riccardino-iii-15\/","title":{"rendered":"Riccardino III"},"content":{"rendered":"<p><em>Scritto e diretto di Gigi Palla<\/em><br \/>\n<em>PRODUZIONE: Politeama s.r.l.<\/em><br \/>\n<em>Adatto ai bambini dai 4 agli 11 anni e per tutti<\/em><\/p>\n<p class=\"elementToProof\">Londra 1450. La corte di Inghilterra \u00e8 in fermento per l\u2019approssimarsi della Giostra del Piccolo Cavaliere, in cui i giovani rampolli della nobilt\u00e0 londinese si affrontano per contendersi il titolo di giovane pretendente alla corona. A contendersi l\u2019agognato titolo tre fratelli di casa York: Edoardino Primo, principe ereditario; Giorgetto secondo, duca di Clarence e Riccardino Terzo, conte di Gloucester. Quest\u2019ultimo, timido, mite e un po\u2019 impacciato \u00e8 preso di mira dai due fratelli, che, pur di primeggiare nelle varie prove, sono disposti ad usare qualsiasi mezzo, lecito ma soprattutto illecito. E mentre le prove sembrano confermare sempre la stessa classifica (Edoardino primo, Giorgetto secondo, Riccardino immancabilmente terzo), tra imbrogli e sabotaggi si arriva alla gara finale che decreter\u00e0 il vincitore: la corsa a cavallo. Riccardino si trover\u00e0 difronte ad un grande dilemma: vincere con l\u2019imbroglio per vendicarsi dei torti subiti, o competere onestamente col rischio di finire ancora una vola \u201cterzo\u201d? Una divertente commedia che coinvolger\u00e0 il pubblico dei pi\u00f9 giovani, facendoli riflettere su temi importanti come la lealt\u00e0, l\u2019onest\u00e0, e l\u2019importanza dell\u2019impegno per raggiungere i propri obiettivi.<\/p>\n<p style=\"text-align: left;\"><strong>CAST<\/strong><br \/>\nEdoardino I: Tommaso Cardarelli<br \/>\nMerlino\/Lady Cristabel: Sergio Mancinelli<br \/>\nGiorgetto II: Valentina Marziali<br \/>\nHastings\/Riccardo III: Gabriela Pratic\u00f2<br \/>\nCiambellano: Gigi Palla<\/p>\n","protected":false},"excerpt":{"rendered":"Scritto e diretto di Gigi Palla PRODUZIONE: Politeama s.r.l. Adatto ai bambini dai 4 agli 11 anni e per tutti Londra 1450. La corte di Inghilterra \u00e8 in fermento per l\u2019approssimarsi della Giostra del Piccolo Cavaliere, in cui i giovani rampolli della nobilt\u00e0 londinese si affrontano per contendersi il titolo di giovane pretendente alla corona. [&hellip;]","protected":false},"featured_media":36285,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[16],"event_genre":[69],"event_themes":[],"event_format":[],"event_consigliati":[],"class_list":["post-36284","event","type-event","status-publish","has-post-thumbnail","hentry","event_categories-teatro","event_genre-teatro"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Riccardino III | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/riccardino-iii-15\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riccardino III | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Scritto e diretto di Gigi Palla PRODUZIONE: Politeama s.r.l. Adatto ai bambini dai 4 agli 11 anni e per tutti Londra 1450. La corte di Inghilterra \u00e8 in fermento per l\u2019approssimarsi della Giostra del Piccolo Cavaliere, in cui i giovani rampolli della nobilt\u00e0 londinese si affrontano per contendersi il titolo di giovane pretendente alla corona. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/riccardino-iii-15\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-18T19:59:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/11\/Schermata-2021-07-05-alle-23.21.53-700x462.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"462\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/riccardino-iii-15\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/riccardino-iii-15\\\/\",\"name\":\"Riccardino III | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/riccardino-iii-15\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/riccardino-iii-15\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Schermata-2021-07-05-alle-23.21.53.png\",\"datePublished\":\"2024-11-13T15:10:28+00:00\",\"dateModified\":\"2024-12-18T19:59:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/riccardino-iii-15\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/riccardino-iii-15\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/riccardino-iii-15\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Schermata-2021-07-05-alle-23.21.53.png\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Schermata-2021-07-05-alle-23.21.53.png\",\"width\":1668,\"height\":1100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/riccardino-iii-15\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Riccardino III\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Riccardino III | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/riccardino-iii-15\/","og_locale":"it_IT","og_type":"article","og_title":"Riccardino III | Auditorium Parco della Musica Ennio Morricone","og_description":"Scritto e diretto di Gigi Palla PRODUZIONE: Politeama s.r.l. Adatto ai bambini dai 4 agli 11 anni e per tutti Londra 1450. La corte di Inghilterra \u00e8 in fermento per l\u2019approssimarsi della Giostra del Piccolo Cavaliere, in cui i giovani rampolli della nobilt\u00e0 londinese si affrontano per contendersi il titolo di giovane pretendente alla corona. [&hellip;]","og_url":"https:\/\/www.auditorium.com\/it\/event\/riccardino-iii-15\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2024-12-18T19:59:35+00:00","og_image":[{"width":700,"height":462,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/11\/Schermata-2021-07-05-alle-23.21.53-700x462.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/riccardino-iii-15\/","url":"https:\/\/www.auditorium.com\/it\/event\/riccardino-iii-15\/","name":"Riccardino III | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/riccardino-iii-15\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/riccardino-iii-15\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/11\/Schermata-2021-07-05-alle-23.21.53.png","datePublished":"2024-11-13T15:10:28+00:00","dateModified":"2024-12-18T19:59:35+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/riccardino-iii-15\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/riccardino-iii-15\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/riccardino-iii-15\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/11\/Schermata-2021-07-05-alle-23.21.53.png","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/11\/Schermata-2021-07-05-alle-23.21.53.png","width":1668,"height":1100},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/riccardino-iii-15\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Riccardino III"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/36284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/36285"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=36284"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=36284"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=36284"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=36284"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=36284"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=36284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}