{"id":36099,"date":"2024-11-06T11:21:28","date_gmt":"2024-11-06T10:21:28","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=36099"},"modified":"2024-11-29T09:01:50","modified_gmt":"2024-11-29T08:01:50","slug":"clown-in-liberta-2","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/clown-in-liberta-2\/","title":{"rendered":"Clown in libert\u00e0"},"content":{"rendered":"<p><em><strong>DI<\/strong> e <strong>CON<\/strong> Leonardo Adorni, Jacopo Maria Bianchini &amp; Alessandro Mori<\/em><br \/>\n<em><strong>Produzione di\u00a0<\/strong>Teatro Necessario<\/em><br \/>\n<em>Spettacolo tout public durata 60 minuti<\/em><\/p>\n<p>Tornano a grande richiesta i tre folli acrobati-musicisti del Teatro Necessario con &#8220;Clown in libert\u00e0&#8221;, lo spettacolo che ha stupito ed esaltato platee di tutto il mondo e ottenuto i pi\u00f9 importanti premi internazionali. &#8220;Clown in libert\u00e0&#8221; \u00e8 un momento di euforia, ricreazione e ritualit\u00e0 catartica per tre talentuosi clown colti da un\u2019eccitazione infantile all\u2019idea di avere una scena ed un pubblico a loro completa disposizione. Ecco quindi sequenze di mano a mano, duelli al rallentatore, intricati passaggi di giocoleria, coreografie acrobatiche e ancora evoluzioni e piramidi. Senza un racconto enunciato e senza alcuno scambio di battute, &#8220;Clown in libert\u00e0&#8221; racconta il pomeriggio di tre clown che vogliono allestire uno spettacolo per divertire, stupire e infine conquistare, abbracciare, baciare il pubblico. La musica \u00e8 la vera colonna portante dell\u2019azione e dello sviluppo narrativo; accompagna, scandisce e ritma ogni segmento ed ogni azione. L\u2019intero spettacolo risulta cos\u00ec come un grande, unico e continuo viaggio musicale che non si interrompe quasi mai, nemmeno durante le acrobazie pi\u00f9 impensabili.<\/p>\n","protected":false},"excerpt":{"rendered":"Tornano a grande richiesta i tre folli acrobati-musicisti del Teatro Necessario con &#8220;Clown in libert\u00e0&#8221;.","protected":false},"featured_media":36163,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[],"event_genre":[242],"event_themes":[],"event_format":[75],"event_consigliati":[],"class_list":["post-36099","event","type-event","status-publish","has-post-thumbnail","hentry","event_genre-circo-contemporaneo","event_format-rassegne"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Clown in libert\u00e0 | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"description\" content=\"Tornano a grande richiesta i tre folli acrobati-musicisti del Teatro Necessario con &quot;Clown in libert\u00e0&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/clown-in-liberta-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Clown in libert\u00e0 | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Tornano a grande richiesta i tre folli acrobati-musicisti del Teatro Necessario con &quot;Clown in libert\u00e0&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/clown-in-liberta-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-29T08:01:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/11\/Unknown.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/clown-in-liberta-2\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/clown-in-liberta-2\\\/\",\"name\":\"Clown in libert\u00e0 | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/clown-in-liberta-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/clown-in-liberta-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Unknown.png\",\"datePublished\":\"2024-11-06T10:21:28+00:00\",\"dateModified\":\"2024-11-29T08:01:50+00:00\",\"description\":\"Tornano a grande richiesta i tre folli acrobati-musicisti del Teatro Necessario con \\\"Clown in libert\u00e0\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/clown-in-liberta-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/clown-in-liberta-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/clown-in-liberta-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Unknown.png\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Unknown.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/clown-in-liberta-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Clown in libert\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Clown in libert\u00e0 | Auditorium Parco della Musica Ennio Morricone","description":"Tornano a grande richiesta i tre folli acrobati-musicisti del Teatro Necessario con \"Clown in libert\u00e0\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/clown-in-liberta-2\/","og_locale":"it_IT","og_type":"article","og_title":"Clown in libert\u00e0 | Auditorium Parco della Musica Ennio Morricone","og_description":"Tornano a grande richiesta i tre folli acrobati-musicisti del Teatro Necessario con \"Clown in libert\u00e0\".","og_url":"https:\/\/www.auditorium.com\/it\/event\/clown-in-liberta-2\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2024-11-29T08:01:50+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/11\/Unknown.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/clown-in-liberta-2\/","url":"https:\/\/www.auditorium.com\/it\/event\/clown-in-liberta-2\/","name":"Clown in libert\u00e0 | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/clown-in-liberta-2\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/clown-in-liberta-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/11\/Unknown.png","datePublished":"2024-11-06T10:21:28+00:00","dateModified":"2024-11-29T08:01:50+00:00","description":"Tornano a grande richiesta i tre folli acrobati-musicisti del Teatro Necessario con \"Clown in libert\u00e0\".","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/clown-in-liberta-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/clown-in-liberta-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/clown-in-liberta-2\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/11\/Unknown.png","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/11\/Unknown.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/clown-in-liberta-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Clown in libert\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/36099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/36163"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=36099"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=36099"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=36099"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=36099"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=36099"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=36099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}