{"id":35904,"date":"2024-10-29T11:10:39","date_gmt":"2024-10-29T10:10:39","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=35904"},"modified":"2024-12-30T13:14:57","modified_gmt":"2024-12-30T12:14:57","slug":"se-dico-circo-5","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/se-dico-circo-5\/","title":{"rendered":"Se dico circo \u2013 Gran Gala Internazionale di Circo Contemporaneo"},"content":{"rendered":"<p>&#8220;Se dico circo \u2013 Gran Gala Internazionale di Circo Contemporaneo&#8221; \u00e8 un\u2019antologia dedicata a questo nuovo linguaggio, che ha il carattere di una festa del circo con tutta la sua variet\u00e0 di talenti. Dai virtuosismi aerei alla giocoleria, dal verticalismo al clown contemporaneo, dalla magie nouvelle alle discipline acrobatiche, il Gran Gala Internazionale di Circo Contemporaneo presenta alcune tra le pi\u00f9 celebri specialit\u00e0 circensi eseguite dai loro massimi esponenti. Composto e condotto dall\u2019artista multidisciplinare <strong>Giacomo Costantini<\/strong>, tra i pionieri di questa materia in Italia, lo spettacolo \u00e8 un\u2019occasione imperdibile per scoprire tutta la magia del circo contemporaneo in un\u2019unica serata.<\/p>\n<p><em><strong>Ideazione e conduzione di<\/strong> Giacomo Costantini<\/em><br \/>\n<em><b>CON <\/b>Guenda Bournens (cerchio aereo), Nicolas Benezech \u00a0(cinghie aeree), Gael Manipoud (rue cyr), Alice Mangili (acrobatica aerea), Novas (magia), Walter Orfei Nones Malachikhine (verticalismo), Fabrizio Rosselli (clown contemporaneo) e Fabrizio Solinas (giocoleria)<\/em><br \/>\n<em><strong>Luci:<\/strong> Domenico De Vita<\/em><\/p>\n<p><strong>pianoforte<\/strong>: Lucio Perotti<\/p>\n<p><em><strong>Prodotto da<\/strong> SIC \u2013 Stabile di Innovazione Circense<\/em><br \/>\n<em><strong>Co-prodotto da<\/strong> Fondazione Musica per Roma<\/em><br \/>\n<em><strong>Realizzato grazie al sostegno di<\/strong>\u00a0MiC \u2013 Ministero Italiano della Cultura<\/em><br \/>\n<em><strong>Spettacolo tout public<\/strong> \u2013 Durata: 75 minuti<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"&#8220;Se dico circo&#8221; \u00e8 un\u2019antologia dedicata a questo nuovo linguaggio, che ha il carattere di una festa con tutta la sua variet\u00e0 di talenti.","protected":false},"featured_media":36428,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[],"event_genre":[242],"event_themes":[],"event_format":[75],"event_consigliati":[],"class_list":["post-35904","event","type-event","status-publish","has-post-thumbnail","hentry","event_genre-circo-contemporaneo","event_format-rassegne"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se dico circo \u2013 Gran Gala Internazionale di Circo Contemporaneo | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"description\" content=\"&quot;Se dico circo&quot; \u00e8 un\u2019antologia dedicata a questo nuovo linguaggio, che ha il carattere di una festa con tutta la sua variet\u00e0 di talenti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/se-dico-circo-5\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se dico circo \u2013 Gran Gala Internazionale di Circo Contemporaneo | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"&quot;Se dico circo&quot; \u00e8 un\u2019antologia dedicata a questo nuovo linguaggio, che ha il carattere di una festa con tutta la sua variet\u00e0 di talenti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/se-dico-circo-5\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-30T12:14:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/10\/1920x1080_BLU_web3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/se-dico-circo-5\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/se-dico-circo-5\\\/\",\"name\":\"Se dico circo \u2013 Gran Gala Internazionale di Circo Contemporaneo | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/se-dico-circo-5\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/se-dico-circo-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1920x1080_BLU_web3.jpg\",\"datePublished\":\"2024-10-29T10:10:39+00:00\",\"dateModified\":\"2024-12-30T12:14:57+00:00\",\"description\":\"\\\"Se dico circo\\\" \u00e8 un\u2019antologia dedicata a questo nuovo linguaggio, che ha il carattere di una festa con tutta la sua variet\u00e0 di talenti.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/se-dico-circo-5\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/se-dico-circo-5\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/se-dico-circo-5\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1920x1080_BLU_web3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1920x1080_BLU_web3.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/se-dico-circo-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se dico circo \u2013 Gran Gala Internazionale di Circo Contemporaneo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se dico circo \u2013 Gran Gala Internazionale di Circo Contemporaneo | Auditorium Parco della Musica Ennio Morricone","description":"\"Se dico circo\" \u00e8 un\u2019antologia dedicata a questo nuovo linguaggio, che ha il carattere di una festa con tutta la sua variet\u00e0 di talenti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/se-dico-circo-5\/","og_locale":"it_IT","og_type":"article","og_title":"Se dico circo \u2013 Gran Gala Internazionale di Circo Contemporaneo | Auditorium Parco della Musica Ennio Morricone","og_description":"\"Se dico circo\" \u00e8 un\u2019antologia dedicata a questo nuovo linguaggio, che ha il carattere di una festa con tutta la sua variet\u00e0 di talenti.","og_url":"https:\/\/www.auditorium.com\/it\/event\/se-dico-circo-5\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2024-12-30T12:14:57+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/10\/1920x1080_BLU_web3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/se-dico-circo-5\/","url":"https:\/\/www.auditorium.com\/it\/event\/se-dico-circo-5\/","name":"Se dico circo \u2013 Gran Gala Internazionale di Circo Contemporaneo | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/se-dico-circo-5\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/se-dico-circo-5\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/10\/1920x1080_BLU_web3.jpg","datePublished":"2024-10-29T10:10:39+00:00","dateModified":"2024-12-30T12:14:57+00:00","description":"\"Se dico circo\" \u00e8 un\u2019antologia dedicata a questo nuovo linguaggio, che ha il carattere di una festa con tutta la sua variet\u00e0 di talenti.","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/se-dico-circo-5\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/se-dico-circo-5\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/se-dico-circo-5\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/10\/1920x1080_BLU_web3.jpg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/10\/1920x1080_BLU_web3.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/se-dico-circo-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Se dico circo \u2013 Gran Gala Internazionale di Circo Contemporaneo"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/35904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/36428"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=35904"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=35904"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=35904"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=35904"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=35904"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=35904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}