{"id":35840,"date":"2024-10-23T17:00:46","date_gmt":"2024-10-23T16:00:46","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=35840"},"modified":"2024-11-09T10:19:22","modified_gmt":"2024-11-09T09:19:22","slug":"stefano-bollani-6","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/stefano-bollani-6\/","title":{"rendered":"Stefano Bollani"},"content":{"rendered":"<p style=\"font-weight: 400;\"><strong>Stefano Bollani<\/strong> torna a Roma, all\u2019Auditorium Parco della Musica Ennio Morricone in Sala Santa Cecilia, con uno speciale appuntamento per celebrare il periodo festivo, gioved\u00ec 26 dicembre 2024. Il concerto far\u00e0 parte del cartellone di Natale in Auditorium, la rassegna natalizia organizzata dalla Fondazione Musica per Roma. Un serata unica nel suo genere fra musiche del presente e musiche del passato, un omaggio all\u2019improvvisazione e al divertimento in pieno stile <strong>Bollani<\/strong>. Il concerto del 26 dicembre concluder\u00e0 un anno ricco di successi musicali per il pianista, reduce dai prestigiosi appuntamenti dello scorso autunno\u00a0 quali\u00a0 i concerti alla Chamber Music Hall di Berlino, alla Kirche Neum\u00fcnster di Zurigo e al Conservatorio G. Verdi di Milano.<\/p>\n<p style=\"font-weight: 400;\">Musica come enorme gioco da re-inventare in continuazione, da solo o con i partners pi\u00f9 diversi. <strong>Bollani<\/strong> cerca stimoli in tutta la musica del passato ma soprattutto esplora il presente, l\u2019attimo, improvvisando a fianco di grandi artisti come il suo nobile mentore E<strong>nrico Rava, Chick Corea, Richard Galliano, Bill Frisell, Lee Konitz, Paul Motian, Pat Metheny<\/strong>, incidendo per le etichette di jazz pi\u00f9 prestigiose quali ECM, Label Bleu e ACT records. Con lo stesso animo gioioso collabora con orchestre sinfoniche come la Gewandhaus di Leipzig, la Scala di Milano e l\u2019 Orchestre National de Paris suonando musiche dei suoi prediletti <strong>Gershwin, Ravel e Poulenc<\/strong>. Si fa prendere per mano da direttori coraggiosi e entusiasti come <strong>Riccardo Chailly, Krjstian Jarvi, Daniel Harding, Zubin Mehta, Anthony Pappano<\/strong>. In tv, dopo l\u2019 esperienza alla corte del grande <strong>Renzo Arbore<\/strong>, ha condotto programmi-jam session di parole e musica (<em>Sostiene Bollan<\/em>i su Rai3 e\u00a0<em>L\u2019 importante \u00e8 avere un piano<\/em> su Rai1). Dal 2021, su Rai3, conduce insieme a Valentina Cenni\u00a0<em>Via dei matti n\u00b00<\/em>, una striscia quotidiana pre-serale di grande successo dedicata alla musica giunta alla quarta edizione. Al festival del cinema di Venezia 2022 \u00e8 stato insignito del prestigioso premio della critica Soundtrack Stars Award per la sua attivit\u00e0 di compositore per i film, premiata anche con un Nastro d&#8217;argento nel 2021 (per\u00a0<em>Carosello Caroson<\/em>e) e con ll David di Donatello nel 2023 (per\u00a0<em>Il pataffio<\/em>).<\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"Stefano Bollani torna a Roma, all\u2019Auditorium Parco della Musica Ennio Morricone in Sala Santa Cecilia, con uno speciale appuntamento per celebrare il periodo festivo, gioved\u00ec 26 dicembre 2024. Il concerto far\u00e0 parte del cartellone di Natale in Auditorium, la rassegna natalizia organizzata dalla Fondazione Musica per Roma. Un serata unica nel suo genere fra musiche [&hellip;]","protected":false},"featured_media":36109,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[82],"event_genre":[63],"event_themes":[],"event_format":[74],"event_consigliati":[],"class_list":["post-35840","event","type-event","status-publish","has-post-thumbnail","hentry","event_categories-dautore","event_genre-autore","event_format-festival"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stefano Bollani | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/stefano-bollani-6\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stefano Bollani | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Stefano Bollani torna a Roma, all\u2019Auditorium Parco della Musica Ennio Morricone in Sala Santa Cecilia, con uno speciale appuntamento per celebrare il periodo festivo, gioved\u00ec 26 dicembre 2024. Il concerto far\u00e0 parte del cartellone di Natale in Auditorium, la rassegna natalizia organizzata dalla Fondazione Musica per Roma. Un serata unica nel suo genere fra musiche [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/stefano-bollani-6\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-09T09:19:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/10\/Press-5-ph_-Azzurra-Primavera-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/stefano-bollani-6\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/stefano-bollani-6\\\/\",\"name\":\"Stefano Bollani | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/stefano-bollani-6\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/stefano-bollani-6\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Press-5-ph_-Azzurra-Primavera-scaled.jpg\",\"datePublished\":\"2024-10-23T16:00:46+00:00\",\"dateModified\":\"2024-11-09T09:19:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/stefano-bollani-6\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/stefano-bollani-6\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/stefano-bollani-6\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Press-5-ph_-Azzurra-Primavera-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Press-5-ph_-Azzurra-Primavera-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"STEFANO BOLLANI\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/stefano-bollani-6\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stefano Bollani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stefano Bollani | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/stefano-bollani-6\/","og_locale":"it_IT","og_type":"article","og_title":"Stefano Bollani | Auditorium Parco della Musica Ennio Morricone","og_description":"Stefano Bollani torna a Roma, all\u2019Auditorium Parco della Musica Ennio Morricone in Sala Santa Cecilia, con uno speciale appuntamento per celebrare il periodo festivo, gioved\u00ec 26 dicembre 2024. Il concerto far\u00e0 parte del cartellone di Natale in Auditorium, la rassegna natalizia organizzata dalla Fondazione Musica per Roma. Un serata unica nel suo genere fra musiche [&hellip;]","og_url":"https:\/\/www.auditorium.com\/it\/event\/stefano-bollani-6\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2024-11-09T09:19:22+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/10\/Press-5-ph_-Azzurra-Primavera-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/stefano-bollani-6\/","url":"https:\/\/www.auditorium.com\/it\/event\/stefano-bollani-6\/","name":"Stefano Bollani | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/stefano-bollani-6\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/stefano-bollani-6\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/10\/Press-5-ph_-Azzurra-Primavera-scaled.jpg","datePublished":"2024-10-23T16:00:46+00:00","dateModified":"2024-11-09T09:19:22+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/stefano-bollani-6\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/stefano-bollani-6\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/stefano-bollani-6\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/10\/Press-5-ph_-Azzurra-Primavera-scaled.jpg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/10\/Press-5-ph_-Azzurra-Primavera-scaled.jpg","width":2560,"height":1707,"caption":"STEFANO BOLLANI"},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/stefano-bollani-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Stefano Bollani"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/35840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/36109"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=35840"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=35840"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=35840"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=35840"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=35840"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=35840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}