{"id":29749,"date":"2017-11-17T18:48:44","date_gmt":"2017-11-17T17:48:44","guid":{"rendered":"https:\/\/www.auditorium.com\/event\/luglio-suona-bene-kids\/"},"modified":"2017-11-17T18:48:44","modified_gmt":"2017-11-17T17:48:44","slug":"luglio-suona-bene-kids","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/luglio-suona-bene-kids\/","title":{"rendered":"Luglio suona bene Kids"},"content":{"rendered":"<p>Fondazione Musica per Roma in collaborazione con Family Welcome<\/p>\n<p>Per ogni appuntamento di Luglio Suona Bene \u00e8 prevista una serata divertente, coinvolgente e istruttiva per ragazzi dai 5 ai 12 anni. Non un baby parking ma uno spazio ludico e creativo di grande impatto. L\u2019iniziativa, promossa dalla Fondazione Musica per Roma, \u00e8 stata organizzata in collaborazione con Family Welcome, una tra le realt\u00e0 editoriali pi\u00f9 innovative sul web dedicate al mondo delle famiglie.<\/p>\n<p>GIUGNO<\/p>\n<p>17 Giugno Cartoons Party<br \/>\nore 21 concerto Bastille<\/p>\n<p>20 Giugno Yoga Per Bambini<br \/>\nore 21 spettacolo Shantala Shivalingappa<\/p>\n<p>22 Giugno Cucinando a suon di musica<br \/>\nore 21 concerto Michael Kiwanuka<\/p>\n<p>23 Giugno Serata Magica<br \/>\nore 20 concerto Jethro Tull<\/p>\n<p>27 Giugno Pigiama Party<br \/>\nore 21 concerto The Beach Boys<\/p>\n<p>28 Giugno Art &#038; Craft<br \/>\nore 21 concerto Clean Bandit Support JP Cooper<\/p>\n<p>29 Giugno Ballerini e Ballerine: dall\u2019hip hop al folk<br \/>\nore 21 concerto Opi, Ambrogio Sparagna<\/p>\n<p>30 Giugno Aladin Party<br \/>\nore 20 concerto Le Mille e una Notte<br \/>\nore 21 concerto Briga<\/p>\n<p>LUGLIO<\/p>\n<p>01 Luglio Karaoke e Disco Party<br \/>\nore 21 concerto Benji &#038; Fede<\/p>\n<p>02 Luglio Il Festival dei Piccoli: Andiamo a Cantare<br \/>\nore 21 concerto Fiorella Mannoia<\/p>\n<p>03 Luglio Pigiama Party<br \/>\nore 21 concerto LP<\/p>\n<p>05 Luglio Cucinando a suon di musica<br \/>\nore 21 concerto Stefano Bollani Sinfonico<\/p>\n<p>08 Luglio Serata Magica<br \/>\nore 21 concerto Bonobo<\/p>\n<p>09 Luglio Caccia al Tesoro<br \/>\nore 21 concerto Francesco Renga<\/p>\n<p>10 Luglio Cucinando a suon di musica<br \/>\nore 21 concerto The Lumineers<\/p>\n<p>11 Luglio Cartoons Party<br \/>\nore 21 concerto Ryan Adams<\/p>\n<p>12 Luglio Cucinando a suon di musica<br \/>\nore 21 concerto Ezio Bosso Sinfonico<\/p>\n<p>13 Luglio Art &#038; Craft<br \/>\nore 21 concerto Nek<\/p>\n<p>14 Luglio Cucinando a suon di musica<br \/>\nore 21 concerto The Pretenders<\/p>\n<p>15 Luglio Il Libro della Giungla<br \/>\nore 21 concerto Francesco Gabbani<\/p>\n<p>16 Luglio Music Painting<br \/>\nore 21 concerto Philip Glass<\/p>\n<p>17 Luglio Cucinando a suon di musica<br \/>\nore 21 concerto Yes<\/p>\n<p>18 Luglio Pigiama Party<br \/>\nore 21 concerto Yann Tiersen<\/p>\n<p>19 Luglio Stasera chi \u00e8 di scena?<br \/>\nore 21 concerto Carmina Burana<\/p>\n<p>20 Luglio Pigiama Party<br \/>\nore 21 concerto Jarabe De Palo<\/p>\n<p>21 Luglio Jazz Story: tutti quanti vogliono fare Jazz<br \/>\nore 21 concerto Gregory Porter<\/p>\n<p>22 Luglio Karaoke Party<br \/>\nore 21 concerto Ermal Meta<\/p>\n<p>23 Luglio Le Cirque De\u2026 La Lune<br \/>\nore 21 concerto Charles Aznavour<\/p>\n<p>24 Luglio Giochi di Strada: come si divertivano i nostri nonni?<br \/>\nore 21 concerto Renzo Arbore l\u2019Orchestra Italiana<\/p>\n<p>25 Luglio Yoga per Bambini<br \/>\nore 21 concerto Benjamin Clementine<\/p>\n<p>26 Luglio Karaoke e Disco Party<br \/>\nore 21 concerto Tom Jones<\/p>\n<p>27 Luglio Cartoons Party<br \/>\nore 21 concerto Carmen Consoli<\/p>\n<p>28 Luglio La carica dei 101<br \/>\nore 20 concerto Brit Floyd<br \/>\nore 21 concerto Al Bano e Romina Power<\/p>\n<p>29 Luglio Carnival Party<br \/>\nore 21 concerto The Divine Comedy<\/p>\n<p>30 Luglio Sognando i Caraibi<br \/>\nore 21 concerto \u00c1lvaro Soler<\/p>\n<p>31 Luglio Music Painting<br \/>\nore 21 concerto Alex Britti &#038; Max Gazz\u00e8<\/p>\n<p>AGOSTO<\/p>\n<p>01 Agosto Yoga per Bambini<br \/>\nore 21 concerto Alex Britti &#038; Max Gazz\u00e8<\/p>\n<p>03 Agosto La Notte della Taranta<br \/>\nore 21 concerto La Notte delle Tammorre<\/p>\n","protected":false},"excerpt":{"rendered":"Fondazione Musica per Roma in collaborazione con Family Welcome Per ogni appuntamento di Luglio Suona Bene \u00e8 prevista una serata divertente, coinvolgente e istruttiva per ragazzi dai 5 ai 12 anni. Non un baby parking ma uno spazio ludico e creativo di grande impatto. L\u2019iniziativa, promossa dalla Fondazione Musica per Roma, \u00e8 stata organizzata in [&hellip;]","protected":false},"featured_media":29750,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[218],"event_genre":[],"event_themes":[],"event_format":[],"event_consigliati":[],"class_list":["post-29749","event","type-event","status-publish","has-post-thumbnail","hentry","event_categories-incontri"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Luglio suona bene Kids | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/luglio-suona-bene-kids\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luglio suona bene Kids | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Fondazione Musica per Roma in collaborazione con Family Welcome Per ogni appuntamento di Luglio Suona Bene \u00e8 prevista una serata divertente, coinvolgente e istruttiva per ragazzi dai 5 ai 12 anni. Non un baby parking ma uno spazio ludico e creativo di grande impatto. L\u2019iniziativa, promossa dalla Fondazione Musica per Roma, \u00e8 stata organizzata in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/luglio-suona-bene-kids\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/09\/16301_lugliosuonabenekids.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/luglio-suona-bene-kids\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/luglio-suona-bene-kids\\\/\",\"name\":\"Luglio suona bene Kids | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/luglio-suona-bene-kids\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/luglio-suona-bene-kids\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/16301_lugliosuonabenekids.jpg\",\"datePublished\":\"2017-11-17T17:48:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/luglio-suona-bene-kids\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/luglio-suona-bene-kids\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/luglio-suona-bene-kids\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/16301_lugliosuonabenekids.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/16301_lugliosuonabenekids.jpg\",\"width\":1920,\"height\":850},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/luglio-suona-bene-kids\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Luglio suona bene Kids\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luglio suona bene Kids | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/luglio-suona-bene-kids\/","og_locale":"it_IT","og_type":"article","og_title":"Luglio suona bene Kids | Auditorium Parco della Musica Ennio Morricone","og_description":"Fondazione Musica per Roma in collaborazione con Family Welcome Per ogni appuntamento di Luglio Suona Bene \u00e8 prevista una serata divertente, coinvolgente e istruttiva per ragazzi dai 5 ai 12 anni. Non un baby parking ma uno spazio ludico e creativo di grande impatto. L\u2019iniziativa, promossa dalla Fondazione Musica per Roma, \u00e8 stata organizzata in [&hellip;]","og_url":"https:\/\/www.auditorium.com\/it\/event\/luglio-suona-bene-kids\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","og_image":[{"width":1920,"height":850,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/09\/16301_lugliosuonabenekids.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/luglio-suona-bene-kids\/","url":"https:\/\/www.auditorium.com\/it\/event\/luglio-suona-bene-kids\/","name":"Luglio suona bene Kids | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/luglio-suona-bene-kids\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/luglio-suona-bene-kids\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/09\/16301_lugliosuonabenekids.jpg","datePublished":"2017-11-17T17:48:44+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/luglio-suona-bene-kids\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/luglio-suona-bene-kids\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/luglio-suona-bene-kids\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/09\/16301_lugliosuonabenekids.jpg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/09\/16301_lugliosuonabenekids.jpg","width":1920,"height":850},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/luglio-suona-bene-kids\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Luglio suona bene Kids"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/29749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/29750"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=29749"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=29749"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=29749"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=29749"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=29749"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=29749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}