{"id":28400,"date":"2017-11-28T14:27:26","date_gmt":"2017-11-28T13:27:26","guid":{"rendered":"https:\/\/www.auditorium.com\/event\/marco-liotti-fifty-fifty\/"},"modified":"2017-11-28T14:27:26","modified_gmt":"2017-11-28T13:27:26","slug":"marco-liotti-fifty-fifty","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/marco-liotti-fifty-fifty\/","title":{"rendered":"Marco Liotti &#038; Fifty Fifty"},"content":{"rendered":"<p>Uno spettacolo coinvolgente con la reinterpretazione live delle pi\u00f9 belle e celebri canzoni degli anni &#8217;50 e \u201860 di autori come Paul Anka, Neil Sedaka, Lloyd Price all&#8217;insegna del puro rock&#8217;n&#8217;roll, swing e doo-wop.<br \/>\nAlcuni brani sono suonati e cantati utilizzando strumenti base in simbiosi con cori maschili, proprio come accadeva allora, mentre altri sono rielaborati dalla band con arrangiamenti contemporanei. Marco Liotti &#038; Fifty Fifty sono in uscita con il loro nuovo cd dal titolo &#8220;Vieni Fuori&#8221;, contenente nove remake e l&#8217;inedito &#8220;Aspettando te&#8221;. Marco \u00e8 da sempre molto attivo in campo discografico. Qualche anno fa ha pubblicato il singolo &#8220;Tu non lo sai&#8221;, versione italiana della canzone &#8220;Breaking up is hard to do&#8221; di Neil Sedaka, che fu programmato da molte radio nazionali e, in particolare, da Fiorello in &#8220;Viva Radio 2&#8221;. Inoltre, in contemporanea con l&#8217;uscita del singolo &#8220;Sei come sei&#8221;, Marco ha interpretato sul grande schermo &#8220;Quando Quando Quando&#8221; di Tony Renis nel film &#8220;Nine&#8221; diretto da Rob Marshall con un cast di star come Daniel Day Lewis, Nicol Kidman, Penelope Cruz e Marion Cotillard.<\/p>\n","protected":false},"excerpt":{"rendered":"Uno spettacolo coinvolgente con la reinterpretazione live delle pi\u00f9 belle e celebri canzoni degli anni &#8217;50 e \u201860 di autori come Paul Anka, Neil Sedaka, Lloyd Price all&#8217;insegna del puro rock&#8217;n&#8217;roll, swing e doo-wop. Alcuni brani sono suonati e cantati utilizzando strumenti base in simbiosi con cori maschili, proprio come accadeva allora, mentre altri sono [&hellip;]","protected":false},"featured_media":28401,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[56],"event_genre":[],"event_themes":[],"event_format":[],"event_consigliati":[],"class_list":["post-28400","event","type-event","status-publish","has-post-thumbnail","hentry","event_categories-musica-classica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marco Liotti &amp; Fifty Fifty | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/marco-liotti-fifty-fifty\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marco Liotti &amp; Fifty Fifty | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Uno spettacolo coinvolgente con la reinterpretazione live delle pi\u00f9 belle e celebri canzoni degli anni &#8217;50 e \u201860 di autori come Paul Anka, Neil Sedaka, Lloyd Price all&#8217;insegna del puro rock&#8217;n&#8217;roll, swing e doo-wop. Alcuni brani sono suonati e cantati utilizzando strumenti base in simbiosi con cori maschili, proprio come accadeva allora, mentre altri sono [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/marco-liotti-fifty-fifty\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/09\/17236_marco_liotti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/marco-liotti-fifty-fifty\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/marco-liotti-fifty-fifty\\\/\",\"name\":\"Marco Liotti & Fifty Fifty | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/marco-liotti-fifty-fifty\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/marco-liotti-fifty-fifty\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/17236_marco_liotti.jpg\",\"datePublished\":\"2017-11-28T13:27:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/marco-liotti-fifty-fifty\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/marco-liotti-fifty-fifty\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/marco-liotti-fifty-fifty\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/17236_marco_liotti.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/17236_marco_liotti.jpg\",\"width\":1920,\"height\":850},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/marco-liotti-fifty-fifty\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marco Liotti &#038; Fifty Fifty\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marco Liotti & Fifty Fifty | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/marco-liotti-fifty-fifty\/","og_locale":"it_IT","og_type":"article","og_title":"Marco Liotti & Fifty Fifty | Auditorium Parco della Musica Ennio Morricone","og_description":"Uno spettacolo coinvolgente con la reinterpretazione live delle pi\u00f9 belle e celebri canzoni degli anni &#8217;50 e \u201860 di autori come Paul Anka, Neil Sedaka, Lloyd Price all&#8217;insegna del puro rock&#8217;n&#8217;roll, swing e doo-wop. Alcuni brani sono suonati e cantati utilizzando strumenti base in simbiosi con cori maschili, proprio come accadeva allora, mentre altri sono [&hellip;]","og_url":"https:\/\/www.auditorium.com\/it\/event\/marco-liotti-fifty-fifty\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","og_image":[{"width":1920,"height":850,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/09\/17236_marco_liotti.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/marco-liotti-fifty-fifty\/","url":"https:\/\/www.auditorium.com\/it\/event\/marco-liotti-fifty-fifty\/","name":"Marco Liotti & Fifty Fifty | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/marco-liotti-fifty-fifty\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/marco-liotti-fifty-fifty\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/09\/17236_marco_liotti.jpg","datePublished":"2017-11-28T13:27:26+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/marco-liotti-fifty-fifty\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/marco-liotti-fifty-fifty\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/marco-liotti-fifty-fifty\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/09\/17236_marco_liotti.jpg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/09\/17236_marco_liotti.jpg","width":1920,"height":850},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/marco-liotti-fifty-fifty\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Marco Liotti &#038; Fifty Fifty"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/28400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/28401"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=28400"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=28400"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=28400"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=28400"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=28400"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=28400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}