{"id":2423,"date":"2023-01-19T15:08:19","date_gmt":"2023-01-19T14:08:19","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=2423"},"modified":"2023-01-30T15:29:57","modified_gmt":"2023-01-30T14:29:57","slug":"la-tarantella-del-carnevale","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/la-tarantella-del-carnevale\/","title":{"rendered":"La Tarantella del Carnevale"},"content":{"rendered":"<p><em>Un progetto originale di <\/em><br \/>\n<strong>Ambrogio Sparagna<\/strong><br \/>\n<em>per<\/em> <strong>Orchestra Popolare Italiana dell&#8217;Auditorium Parco della Musica<\/strong><br \/>\n<strong>Coro Popolare <\/strong><br \/>\n<em>diretto da <\/em><br \/>\n<strong>Anna Rita Colaianni<\/strong><br \/>\n<strong>Gruppo Danzatori Popolari <\/strong><br \/>\n<em>diretti da<\/em><br \/>\n<strong>Francesca Trenta<\/strong><br \/>\n<em>e con la partecipazione di<\/em><br \/>\n<strong>Le maschere zoomorfe molisane <\/strong><\/p>\n<p><strong>Una produzione originale di Fondazione Musica per Roma<\/strong><\/p>\n<p>Torna la <em>Tarantella del Carnevale:<\/em> una grande festa per tutti, piccoli e grandi, con la partecipazione di maschere e danzatori tradizionali che animeranno a ritmo di travolgenti e vertiginose tarantelle un grande concerto alle ore 11 in Sala Sinopoli e una parata mascherata alle ore 13 negli spazi all\u2019aperto dell\u2019Auditorium. <\/p>\n<p>In questa settima edizione saranno protagoniste le maschere zoomorfe tradizionali, una modalit\u00e0 di rappresentazione carnascialesca ancora largamente diffusa in molte zone del nostro Paese, in particolare nelle aree alpine e appenniniche dove permangono attivit\u00e0 economiche legate alla pastorizia.  Questo tipo di maschera si caratterizza per l\u2019utilizzo di travestimenti dalle sembianze animalesche: orsi, capre, cervi ma anche vestimenti villosi. In questi costumi i segni sonori specifici sono costituiti dall\u2019uso di sonagli di varie proporzioni, costruiti in ferro che con le ossa di animali. La persistenza di questi cerimoniali carnascialeschi arcaici afferma la necessit\u00e0, anche nella nostra cultura contemporanea, di conservare il desiderio dell\u2019uomo di stringere \u2013 o rinnovare \u2013 un patto con le forze della Natura, di \u2018addomesticarle\u2019 e farsele amiche affinch\u00e9 non ostacolino, anzi favoriscano, il benessere della comunit\u00e0. Analogamente si pu\u00f2 dire per le maschere composte di parti vegetali: foglie, corteccia, muschio, paglia e rami che trasformano chi se ne veste in \u201cUomo selvatico\u201d, spirito del bosco che padroneggia le energie vegetative e ha il potere di piegarle a profitto degli esseri umani, sempre che essi gli mostrino la dovuta riverenza e rispetto. Nella tradizione popolare le azioni sceniche che coinvolgono le maschere animali e vegetali contemplano l\u2019uccisione simbolica di queste ultime seguita dalla loro rinascita, e rappresentano il ristabilito \u2018patto\u2019 con il mondo naturale ed il ciclico rinnovarsi dell\u2019anno e della vita. Questo genere di rituali \u00e8 ancora in uso in alcuni piccoli paesi appenninici del Molise. A Tufara (Cb) si celebra l\u2019antica rappresentazione del Diavolo; a Jelsi (Cb) quella dell\u2019Orso e a Castelnuovo Volturno (Is) quella del Cervo. Saranno proprio alcuni gruppi mascherati provenienti dal Molise insieme alle azioni coreutiche realizzate dal gruppo di danzatori popolari, coordinati da Francesca Trenta, a caratterizzare questa settima edizione della <em>Tarantella del Carnevale<\/em>. Un&#8217;occasione speciale per riscoprire gli antichi rituali agricoli che evidenziavano il passaggio dall\u2019Inverno alla Primavera, tempo di risveglio e di fioritura, auspicio e speranza per un raccolto abbondante. Uno spettacolo unico e coinvolgente che offrir\u00e0 una forza rigenerativa, una grande festa originale, ipnotica, travolgente e autenticamente popolare.<\/p>\n","protected":false},"excerpt":{"rendered":"Un progetto originale di Ambrogio Sparagna per Orchestra Popolare Italiana dell&#8217;Auditorium Parco della Musica Coro Popolare diretto da Anna Rita Colaianni Gruppo Danzatori Popolari diretti da Francesca Trenta e con la partecipazione di Le maschere zoomorfe molisane Una produzione originale di Fondazione Musica per Roma Torna la Tarantella del Carnevale: una grande festa per tutti, [&hellip;]","protected":false},"featured_media":2424,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[],"event_genre":[62],"event_themes":[],"event_format":[],"event_consigliati":[],"class_list":["post-2423","event","type-event","status-publish","has-post-thumbnail","hentry","event_genre-crossover"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Tarantella del Carnevale | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/la-tarantella-del-carnevale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Tarantella del Carnevale | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Un progetto originale di Ambrogio Sparagna per Orchestra Popolare Italiana dell&#8217;Auditorium Parco della Musica Coro Popolare diretto da Anna Rita Colaianni Gruppo Danzatori Popolari diretti da Francesca Trenta e con la partecipazione di Le maschere zoomorfe molisane Una produzione originale di Fondazione Musica per Roma Torna la Tarantella del Carnevale: una grande festa per tutti, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/la-tarantella-del-carnevale\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-30T14:29:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/Tarantella-Carnevale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/la-tarantella-del-carnevale\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/la-tarantella-del-carnevale\\\/\",\"name\":\"La Tarantella del Carnevale | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/la-tarantella-del-carnevale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/la-tarantella-del-carnevale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Tarantella-Carnevale.jpg\",\"datePublished\":\"2023-01-19T14:08:19+00:00\",\"dateModified\":\"2023-01-30T14:29:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/la-tarantella-del-carnevale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/la-tarantella-del-carnevale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/la-tarantella-del-carnevale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Tarantella-Carnevale.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Tarantella-Carnevale.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Tarantella-Carnevale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/la-tarantella-del-carnevale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Tarantella del Carnevale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Tarantella del Carnevale | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/la-tarantella-del-carnevale\/","og_locale":"it_IT","og_type":"article","og_title":"La Tarantella del Carnevale | Auditorium Parco della Musica Ennio Morricone","og_description":"Un progetto originale di Ambrogio Sparagna per Orchestra Popolare Italiana dell&#8217;Auditorium Parco della Musica Coro Popolare diretto da Anna Rita Colaianni Gruppo Danzatori Popolari diretti da Francesca Trenta e con la partecipazione di Le maschere zoomorfe molisane Una produzione originale di Fondazione Musica per Roma Torna la Tarantella del Carnevale: una grande festa per tutti, [&hellip;]","og_url":"https:\/\/www.auditorium.com\/it\/event\/la-tarantella-del-carnevale\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2023-01-30T14:29:57+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/Tarantella-Carnevale.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/la-tarantella-del-carnevale\/","url":"https:\/\/www.auditorium.com\/it\/event\/la-tarantella-del-carnevale\/","name":"La Tarantella del Carnevale | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/la-tarantella-del-carnevale\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/la-tarantella-del-carnevale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/Tarantella-Carnevale.jpg","datePublished":"2023-01-19T14:08:19+00:00","dateModified":"2023-01-30T14:29:57+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/la-tarantella-del-carnevale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/la-tarantella-del-carnevale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/la-tarantella-del-carnevale\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/Tarantella-Carnevale.jpg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/Tarantella-Carnevale.jpg","width":1920,"height":1080,"caption":"Tarantella-Carnevale"},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/la-tarantella-del-carnevale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"La Tarantella del Carnevale"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/2423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/2424"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=2423"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=2423"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=2423"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=2423"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=2423"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=2423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}