{"id":23870,"date":"2017-11-17T17:52:53","date_gmt":"2017-11-17T16:52:53","guid":{"rendered":"https:\/\/www.auditorium.com\/event\/i-cinque-uningiustizia-ignorata\/"},"modified":"2017-11-17T17:52:53","modified_gmt":"2017-11-17T16:52:53","slug":"i-cinque-uningiustizia-ignorata","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/i-cinque-uningiustizia-ignorata\/","title":{"rendered":"&#8220;I Cinque: un\u2019ingiustizia ignorata&#8221;"},"content":{"rendered":"<p>Con il Patrocinio di<br \/>\nComune di Roma<br \/>\nRegione Lazio<br \/>\nAmbasciata di Cuba in Italia<\/p>\n<p>L\u2019Associazione Nazionale di Amicizia Italia &#8211; Cuba Circolo di Roma presenta<\/p>\n<p>  Questa \u00e8 la storia di una profonda ingiustizia umana iniziata alla fine degli anni &#8217;90, non ancora conclusa e trasformata in un caso politico giudiziario internazionale incomprensibile se non lo si inserisce nel contesto storico delle relazioni tra gli Stati Uniti e Cuba. La vicenda dei 5 cubani detenuti nelle carceri statunitensi dal 1998 \u00e8 stata e continua ad essere completamente ignorata da tutti gli organi di informazione occidentali. Per questa ragione il Circolo di Roma dell&#8217;ANAIC ha realizzato un evento che raccoglie testimonianze e interventi di personaggi del mondo politico e della cultura, nazionali e internazionali, per informare e sensibilizzare su un caso non solo politico ma anche umano. Alla serata, condotta da Gianni Min\u00e0, interverranno Frei Betto, Wayne Smith, Gianni Vattimo, Rosa Aurora Frijanes Coca, Jonis Bascir, Renata Mezenov Sa e altri ancora.<\/p>\n","protected":false},"excerpt":{"rendered":"Con il Patrocinio di Comune di Roma Regione Lazio Ambasciata di Cuba in Italia L\u2019Associazione Nazionale di Amicizia Italia &#8211; Cuba Circolo di Roma presenta Questa \u00e8 la storia di una profonda ingiustizia umana iniziata alla fine degli anni &#8217;90, non ancora conclusa e trasformata in un caso politico giudiziario internazionale incomprensibile se non lo [&hellip;]","protected":false},"featured_media":23871,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[218],"event_genre":[],"event_themes":[],"event_format":[],"event_consigliati":[],"class_list":["post-23870","event","type-event","status-publish","has-post-thumbnail","hentry","event_categories-incontri"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;I Cinque: un\u2019ingiustizia ignorata&quot; | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/i-cinque-uningiustizia-ignorata\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;I Cinque: un\u2019ingiustizia ignorata&quot; | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Con il Patrocinio di Comune di Roma Regione Lazio Ambasciata di Cuba in Italia L\u2019Associazione Nazionale di Amicizia Italia &#8211; Cuba Circolo di Roma presenta Questa \u00e8 la storia di una profonda ingiustizia umana iniziata alla fine degli anni &#8217;90, non ancora conclusa e trasformata in un caso politico giudiziario internazionale incomprensibile se non lo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/i-cinque-uningiustizia-ignorata\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/09\/13725_cuba.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/i-cinque-uningiustizia-ignorata\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/i-cinque-uningiustizia-ignorata\\\/\",\"name\":\"\\\"I Cinque: un\u2019ingiustizia ignorata\\\" | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/i-cinque-uningiustizia-ignorata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/i-cinque-uningiustizia-ignorata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/13725_cuba.jpg\",\"datePublished\":\"2017-11-17T16:52:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/i-cinque-uningiustizia-ignorata\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/i-cinque-uningiustizia-ignorata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/i-cinque-uningiustizia-ignorata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/13725_cuba.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/13725_cuba.jpg\",\"width\":1920,\"height\":850},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/i-cinque-uningiustizia-ignorata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;I Cinque: un\u2019ingiustizia ignorata&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"I Cinque: un\u2019ingiustizia ignorata\" | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/i-cinque-uningiustizia-ignorata\/","og_locale":"it_IT","og_type":"article","og_title":"\"I Cinque: un\u2019ingiustizia ignorata\" | Auditorium Parco della Musica Ennio Morricone","og_description":"Con il Patrocinio di Comune di Roma Regione Lazio Ambasciata di Cuba in Italia L\u2019Associazione Nazionale di Amicizia Italia &#8211; Cuba Circolo di Roma presenta Questa \u00e8 la storia di una profonda ingiustizia umana iniziata alla fine degli anni &#8217;90, non ancora conclusa e trasformata in un caso politico giudiziario internazionale incomprensibile se non lo [&hellip;]","og_url":"https:\/\/www.auditorium.com\/it\/event\/i-cinque-uningiustizia-ignorata\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","og_image":[{"width":1920,"height":850,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/09\/13725_cuba.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/i-cinque-uningiustizia-ignorata\/","url":"https:\/\/www.auditorium.com\/it\/event\/i-cinque-uningiustizia-ignorata\/","name":"\"I Cinque: un\u2019ingiustizia ignorata\" | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/i-cinque-uningiustizia-ignorata\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/i-cinque-uningiustizia-ignorata\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/09\/13725_cuba.jpg","datePublished":"2017-11-17T16:52:53+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/i-cinque-uningiustizia-ignorata\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/i-cinque-uningiustizia-ignorata\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/i-cinque-uningiustizia-ignorata\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/09\/13725_cuba.jpg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/09\/13725_cuba.jpg","width":1920,"height":850},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/i-cinque-uningiustizia-ignorata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"&#8220;I Cinque: un\u2019ingiustizia ignorata&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/23870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/23871"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=23870"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=23870"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=23870"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=23870"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=23870"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=23870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}