{"id":1920,"date":"2023-01-17T08:14:55","date_gmt":"2023-01-17T07:14:55","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=1920"},"modified":"2023-01-19T12:00:23","modified_gmt":"2023-01-19T11:00:23","slug":"bayadere-il-regno-delle-ombre","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/bayadere-il-regno-delle-ombre\/","title":{"rendered":"Michele Di Stefano &#8220;Bayad\u00e9re &#8211; Il Regno delle ombre&#8221;"},"content":{"rendered":"<p>Bayad\u00e9re e\u0300 un balletto intriso di esotismo idealizzato, sia nella trama melodrammatica che nell\u2019estetica dell\u2019insieme. Pensato per un ensemble di talenti giovanissimi, questo nuovo Regno delle Ombre cosi\u0300 misteriosamente carico di suggestioni, appartiene ai tempi eccezionali che stiamo vivendo, perch\u00e9\u0301 fa riferimento a qualcosa di perduto e a qualcosa di possibile allo stesso tempo, qualcosa che riguarda la presenza dei corpi e l\u2019intreccio delle loro traiettorie, in uno spazio che non e\u0300 pi\u00f9\u0300 soltanto un al di la\u0300 ma e\u0300 un presente che desidera essere reinventato con delicatezza e passione. <br \/>\nNella tradizione la sua scena pi\u00f9\u0300 celebre, il Regno delle Ombre, si presenta borderline al limite tra il reale e l\u2019aldil\u00e0\u0300, dove le ombre che appaiono sono come congelate nella loro tragica condizione e i movimenti che compiono sono rituali; l\u2019atto esprime una visione che esula dal contesto e che apre a un passaggio di puro movimento, astratto e lucido nella sua semplicit\u00e0\u0300 formale. L\u2019interesse dei coreografi e\u0300 rivolto proprio al potenziale compositivo che questa scena contiene, non per replicarla ma per scatenare tutta la sua forza dinamica ed anche per restituire all\u2019allucinazione di Solor la sua vera natura psichedelica. <\/p>\n<p>di Ludwing Minkus e Michele Di Stefano<br \/>\nBalletto in un atto per 12 danzatori \u2013 durata 60 min. circa<br \/>\nCoreografia di Michele Di Stefano Musica di Ludwing Minkus<br \/>\nMusiche originali di Lorenzo Bianchi Hoesch<br \/>\nCostumi Santi Rinciari Luci Giulia Broggi<br \/>\nNuovo Balletto di Toscana<br \/>\nDanzatori: Cristina Acri, Matteo Capetola, Francesca Capurso, Carmine Catalano, Alice Catapano, Beatrice Ciattini, Matilde Di Ciolo, Veronica Galdo, Mattia Luparelli, Aldo Nolli, Niccolo\u0300 Poggini, Paolo Rizzo<\/p>\n","protected":false},"excerpt":{"rendered":"Bayad\u00e9re e\u0300 un balletto intriso di esotismo idealizzato, sia nella trama melodrammatica che nell\u2019estetica dell\u2019insieme. Pensato per un ensemble di talenti giovanissimi, questo nuovo Regno delle Ombre cosi\u0300 misteriosamente carico di suggestioni, appartiene ai tempi eccezionali che stiamo vivendo, perch\u00e9\u0301 fa riferimento a qualcosa di perduto e a qualcosa di possibile allo stesso tempo, qualcosa [&hellip;]","protected":false},"featured_media":1921,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[51],"event_genre":[68],"event_themes":[],"event_format":[74],"event_consigliati":[],"class_list":["post-1920","event","type-event","status-publish","has-post-thumbnail","hentry","event_categories-danza","event_genre-danza","event_format-festival"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Michele Di Stefano &quot;Bayad\u00e9re - Il Regno delle ombre&quot; | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/bayadere-il-regno-delle-ombre\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Michele Di Stefano &quot;Bayad\u00e9re - Il Regno delle ombre&quot; | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Bayad\u00e9re e\u0300 un balletto intriso di esotismo idealizzato, sia nella trama melodrammatica che nell\u2019estetica dell\u2019insieme. Pensato per un ensemble di talenti giovanissimi, questo nuovo Regno delle Ombre cosi\u0300 misteriosamente carico di suggestioni, appartiene ai tempi eccezionali che stiamo vivendo, perch\u00e9\u0301 fa riferimento a qualcosa di perduto e a qualcosa di possibile allo stesso tempo, qualcosa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/bayadere-il-regno-delle-ombre\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-19T11:00:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/11-febbraio_Di-stefano.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/bayadere-il-regno-delle-ombre\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/bayadere-il-regno-delle-ombre\\\/\",\"name\":\"Michele Di Stefano \\\"Bayad\u00e9re - Il Regno delle ombre\\\" | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/bayadere-il-regno-delle-ombre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/bayadere-il-regno-delle-ombre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/11-febbraio_Di-stefano.png\",\"datePublished\":\"2023-01-17T07:14:55+00:00\",\"dateModified\":\"2023-01-19T11:00:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/bayadere-il-regno-delle-ombre\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/bayadere-il-regno-delle-ombre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/bayadere-il-regno-delle-ombre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/11-febbraio_Di-stefano.png\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/11-febbraio_Di-stefano.png\",\"width\":1920,\"height\":1080,\"caption\":\"bayadere\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/bayadere-il-regno-delle-ombre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Michele Di Stefano &#8220;Bayad\u00e9re &#8211; Il Regno delle ombre&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Michele Di Stefano \"Bayad\u00e9re - Il Regno delle ombre\" | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/bayadere-il-regno-delle-ombre\/","og_locale":"it_IT","og_type":"article","og_title":"Michele Di Stefano \"Bayad\u00e9re - Il Regno delle ombre\" | Auditorium Parco della Musica Ennio Morricone","og_description":"Bayad\u00e9re e\u0300 un balletto intriso di esotismo idealizzato, sia nella trama melodrammatica che nell\u2019estetica dell\u2019insieme. Pensato per un ensemble di talenti giovanissimi, questo nuovo Regno delle Ombre cosi\u0300 misteriosamente carico di suggestioni, appartiene ai tempi eccezionali che stiamo vivendo, perch\u00e9\u0301 fa riferimento a qualcosa di perduto e a qualcosa di possibile allo stesso tempo, qualcosa [&hellip;]","og_url":"https:\/\/www.auditorium.com\/it\/event\/bayadere-il-regno-delle-ombre\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2023-01-19T11:00:23+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/11-febbraio_Di-stefano.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/bayadere-il-regno-delle-ombre\/","url":"https:\/\/www.auditorium.com\/it\/event\/bayadere-il-regno-delle-ombre\/","name":"Michele Di Stefano \"Bayad\u00e9re - Il Regno delle ombre\" | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/bayadere-il-regno-delle-ombre\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/bayadere-il-regno-delle-ombre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/11-febbraio_Di-stefano.png","datePublished":"2023-01-17T07:14:55+00:00","dateModified":"2023-01-19T11:00:23+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/bayadere-il-regno-delle-ombre\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/bayadere-il-regno-delle-ombre\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/bayadere-il-regno-delle-ombre\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/11-febbraio_Di-stefano.png","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/11-febbraio_Di-stefano.png","width":1920,"height":1080,"caption":"bayadere"},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/bayadere-il-regno-delle-ombre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Michele Di Stefano &#8220;Bayad\u00e9re &#8211; Il Regno delle ombre&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/1920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/1921"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=1920"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=1920"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=1920"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=1920"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=1920"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=1920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}