{"id":1759,"date":"2023-01-13T15:41:23","date_gmt":"2023-01-13T15:41:23","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=1759"},"modified":"2023-01-31T15:42:11","modified_gmt":"2023-01-31T14:42:11","slug":"mario-brunello-progetto-bach-iv","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/mario-brunello-progetto-bach-iv\/","title":{"rendered":"Mario Brunello &#8211; Progetto Bach IV"},"content":{"rendered":"<p><em>violoncello e violoncello piccolo<\/em> <strong>Mario Brunello<\/strong><\/p>\n<p><strong>Bach: 12 capolavori suonati e spiegati da Mario Brunello \u2013 IV Concerto<\/strong><\/p>\n<p>Suite n. 1 in Sol maggiore per violoncello BWV 1007<br \/>\nSuite n. 3 in Do maggiore per violoncello BWV 1009<br \/>\nSonata n. 3 in Do maggiore per violino BWV 1005<\/p>\n","protected":false},"excerpt":{"rendered":"violoncello e violoncello piccolo Mario Brunello Bach: 12 capolavori suonati e spiegati da Mario Brunello \u2013 IV Concerto Suite n. 1 in Sol maggiore per violoncello BWV 1007 Suite n. 3 in Do maggiore per violoncello BWV 1009 Sonata n. 3 in Do maggiore per violino BWV 1005","protected":false},"featured_media":1760,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[],"event_genre":[60],"event_themes":[],"event_format":[],"event_consigliati":[],"class_list":["post-1759","event","type-event","status-publish","has-post-thumbnail","hentry","event_genre-classica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mario Brunello - Progetto Bach IV | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/mario-brunello-progetto-bach-iv\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mario Brunello - Progetto Bach IV | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"violoncello e violoncello piccolo Mario Brunello Bach: 12 capolavori suonati e spiegati da Mario Brunello \u2013 IV Concerto Suite n. 1 in Sol maggiore per violoncello BWV 1007 Suite n. 3 in Do maggiore per violoncello BWV 1009 Sonata n. 3 in Do maggiore per violino BWV 1005\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/mario-brunello-progetto-bach-iv\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-31T14:42:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/brunello.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"955\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/mario-brunello-progetto-bach-iv\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/mario-brunello-progetto-bach-iv\\\/\",\"name\":\"Mario Brunello - Progetto Bach IV | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/mario-brunello-progetto-bach-iv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/mario-brunello-progetto-bach-iv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/brunello.jpg\",\"datePublished\":\"2023-01-13T15:41:23+00:00\",\"dateModified\":\"2023-01-31T14:42:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/mario-brunello-progetto-bach-iv\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/mario-brunello-progetto-bach-iv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/mario-brunello-progetto-bach-iv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/brunello.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/brunello.jpg\",\"width\":1920,\"height\":955,\"caption\":\"Mario Brunello - Progetto Bach IV\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/mario-brunello-progetto-bach-iv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mario Brunello &#8211; Progetto Bach IV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mario Brunello - Progetto Bach IV | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/mario-brunello-progetto-bach-iv\/","og_locale":"it_IT","og_type":"article","og_title":"Mario Brunello - Progetto Bach IV | Auditorium Parco della Musica Ennio Morricone","og_description":"violoncello e violoncello piccolo Mario Brunello Bach: 12 capolavori suonati e spiegati da Mario Brunello \u2013 IV Concerto Suite n. 1 in Sol maggiore per violoncello BWV 1007 Suite n. 3 in Do maggiore per violoncello BWV 1009 Sonata n. 3 in Do maggiore per violino BWV 1005","og_url":"https:\/\/www.auditorium.com\/it\/event\/mario-brunello-progetto-bach-iv\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2023-01-31T14:42:11+00:00","og_image":[{"width":1920,"height":955,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/brunello.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/mario-brunello-progetto-bach-iv\/","url":"https:\/\/www.auditorium.com\/it\/event\/mario-brunello-progetto-bach-iv\/","name":"Mario Brunello - Progetto Bach IV | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/mario-brunello-progetto-bach-iv\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/mario-brunello-progetto-bach-iv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/brunello.jpg","datePublished":"2023-01-13T15:41:23+00:00","dateModified":"2023-01-31T14:42:11+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/mario-brunello-progetto-bach-iv\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/mario-brunello-progetto-bach-iv\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/mario-brunello-progetto-bach-iv\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/brunello.jpg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/brunello.jpg","width":1920,"height":955,"caption":"Mario Brunello - Progetto Bach IV"},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/mario-brunello-progetto-bach-iv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Mario Brunello &#8211; Progetto Bach IV"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/1759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/1760"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=1759"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=1759"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=1759"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=1759"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=1759"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=1759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}