{"id":1676,"date":"2023-01-13T11:42:13","date_gmt":"2023-01-13T11:42:13","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=1676"},"modified":"2023-01-16T18:57:07","modified_gmt":"2023-01-16T18:57:07","slug":"violoncelli-di-santa-cecilia-kian-soltani","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/violoncelli-di-santa-cecilia-kian-soltani\/","title":{"rendered":"Violoncelli di Santa Cecilia \/ Kian Soltani"},"content":{"rendered":"<p><em>violoncello <\/em><strong>Kian Soltani<\/strong><br \/>\n<em>soprano <\/em><strong>Giuliana Gianfaldoni<\/strong><br \/>\n<strong>Violoncelli dell\u2019Orchestra dell\u2019Accademia di Santa Cecilia<\/strong><\/p>\n<p><strong>Lo spirito europeo<\/strong><br \/>\n<strong>Chesnokov <\/strong>To Thee We Sing op. 27 n. 6<br \/>\n<strong>Vivaldi <\/strong>Concerto per due violoncelli, RV 531<br \/>\n<strong>Piatti <\/strong>Serenata per 2 violoncelli <br \/>\n<strong>R. Strauss<\/strong> Nachtgang op 29. n. 3 <br \/>\n Breit \u00fcber mein Haupt op. 19 n. 2<br \/>\n<strong>Sollima <\/strong>Violoncelles, Vibrez! <\/p>\n<p><strong>South American Getaway<\/strong><br \/>\nGardel Por una Cabeza <br \/>\nVilla-Lobos Aria da Bachianas Brasileiras n. 5<br \/>\nBacharach South American Getaway <br \/>\nPiazzolla Le Quattro Stagioni di Buenos Aires: Inverno e Primavera <br \/>\nTradizionale\/James Barralet Folk off! \u2013 Memories of Europe<\/p>\n<p>Il concerto \u00e8 trasmesso in diretta alle 20.30 da Rai Radio Tre<\/p>\n","protected":false},"excerpt":{"rendered":"violoncello Kian Soltani soprano Giuliana Gianfaldoni Violoncelli dell\u2019Orchestra dell\u2019Accademia di Santa Cecilia Lo spirito europeo Chesnokov To Thee We Sing op. 27 n. 6 Vivaldi Concerto per due violoncelli, RV 531 Piatti Serenata per 2 violoncelli R. Strauss Nachtgang op 29. n. 3 Breit \u00fcber mein Haupt op. 19 n. 2 Sollima Violoncelles, Vibrez! South [&hellip;]","protected":false},"featured_media":1678,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[],"event_genre":[60],"event_themes":[],"event_format":[],"event_consigliati":[],"class_list":["post-1676","event","type-event","status-publish","has-post-thumbnail","hentry","event_genre-classica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Violoncelli di Santa Cecilia \/ Kian Soltani | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/violoncelli-di-santa-cecilia-kian-soltani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Violoncelli di Santa Cecilia \/ Kian Soltani | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"violoncello Kian Soltani soprano Giuliana Gianfaldoni Violoncelli dell\u2019Orchestra dell\u2019Accademia di Santa Cecilia Lo spirito europeo Chesnokov To Thee We Sing op. 27 n. 6 Vivaldi Concerto per due violoncelli, RV 531 Piatti Serenata per 2 violoncelli R. Strauss Nachtgang op 29. n. 3 Breit \u00fcber mein Haupt op. 19 n. 2 Sollima Violoncelles, Vibrez! South [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/violoncelli-di-santa-cecilia-kian-soltani\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-16T18:57:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/soltani-1920-ok-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1273\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/violoncelli-di-santa-cecilia-kian-soltani\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/violoncelli-di-santa-cecilia-kian-soltani\\\/\",\"name\":\"Violoncelli di Santa Cecilia \\\/ Kian Soltani | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/violoncelli-di-santa-cecilia-kian-soltani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/violoncelli-di-santa-cecilia-kian-soltani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/soltani-1920-ok-scaled-1.jpg\",\"datePublished\":\"2023-01-13T11:42:13+00:00\",\"dateModified\":\"2023-01-16T18:57:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/violoncelli-di-santa-cecilia-kian-soltani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/violoncelli-di-santa-cecilia-kian-soltani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/violoncelli-di-santa-cecilia-kian-soltani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/soltani-1920-ok-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/soltani-1920-ok-scaled-1.jpg\",\"width\":2560,\"height\":1273,\"caption\":\"Violoncelli di Santa Cecilia \\\/ Kian Soltani\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/violoncelli-di-santa-cecilia-kian-soltani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Violoncelli di Santa Cecilia \\\/ Kian Soltani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Violoncelli di Santa Cecilia \/ Kian Soltani | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/violoncelli-di-santa-cecilia-kian-soltani\/","og_locale":"it_IT","og_type":"article","og_title":"Violoncelli di Santa Cecilia \/ Kian Soltani | Auditorium Parco della Musica Ennio Morricone","og_description":"violoncello Kian Soltani soprano Giuliana Gianfaldoni Violoncelli dell\u2019Orchestra dell\u2019Accademia di Santa Cecilia Lo spirito europeo Chesnokov To Thee We Sing op. 27 n. 6 Vivaldi Concerto per due violoncelli, RV 531 Piatti Serenata per 2 violoncelli R. Strauss Nachtgang op 29. n. 3 Breit \u00fcber mein Haupt op. 19 n. 2 Sollima Violoncelles, Vibrez! South [&hellip;]","og_url":"https:\/\/www.auditorium.com\/it\/event\/violoncelli-di-santa-cecilia-kian-soltani\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2023-01-16T18:57:07+00:00","og_image":[{"width":2560,"height":1273,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/soltani-1920-ok-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/violoncelli-di-santa-cecilia-kian-soltani\/","url":"https:\/\/www.auditorium.com\/it\/event\/violoncelli-di-santa-cecilia-kian-soltani\/","name":"Violoncelli di Santa Cecilia \/ Kian Soltani | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/violoncelli-di-santa-cecilia-kian-soltani\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/violoncelli-di-santa-cecilia-kian-soltani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/soltani-1920-ok-scaled-1.jpg","datePublished":"2023-01-13T11:42:13+00:00","dateModified":"2023-01-16T18:57:07+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/violoncelli-di-santa-cecilia-kian-soltani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/violoncelli-di-santa-cecilia-kian-soltani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/violoncelli-di-santa-cecilia-kian-soltani\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/soltani-1920-ok-scaled-1.jpg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/01\/soltani-1920-ok-scaled-1.jpg","width":2560,"height":1273,"caption":"Violoncelli di Santa Cecilia \/ Kian Soltani"},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/violoncelli-di-santa-cecilia-kian-soltani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Violoncelli di Santa Cecilia \/ Kian Soltani"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/1676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/1678"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=1676"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=1676"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=1676"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=1676"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=1676"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=1676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}