{"id":13927,"date":"2024-03-06T10:23:24","date_gmt":"2024-03-06T09:23:24","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=13927"},"modified":"2024-03-14T13:54:16","modified_gmt":"2024-03-14T12:54:16","slug":"giorgio-manzi-antenati-con-edoardo-camurri","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/giorgio-manzi-antenati-con-edoardo-camurri\/","title":{"rendered":"Giorgio Manzi \u2013 &#8220;Antenati&#8221; con Edoardo Camurri"},"content":{"rendered":"<p style=\"font-weight: 400; text-align: center;\"><strong>GIORGIO MANZI<\/strong><\/p>\n<p style=\"font-weight: 400; text-align: center;\"><em>Antenati. Lucy e altri racconti dal tempo profondo<\/em><\/p>\n<p style=\"font-weight: 400; text-align: center;\">Il Mulino<\/p>\n<p style=\"font-weight: 400; text-align: center;\">Con <strong>Edoardo Camurri<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\"><strong>Un tuffo nell\u2019archivio della storia prima della storia. Capire chi siamo attraverso i racconti di un grande paleoantropologo intervistato da Edoardo Camurri.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Giorgio Manzi ci regala un racconto avvincente, per spiegarci da un lato come la scienza sia in grado di ricostruire e interpretare la nostra storia nel tempo profondo e, dall\u2019altro, come questo racconto consenta di comprendere meglio chi siamo e quale sia il nostro posto nella natura. Cos\u00ec, insieme a Edoardo Camurri, incontreremo i protagonisti di un lontanissimo passato, messi a confronto con quelli del presente e del futuro. Ispirato da Richard Dawkins (\u00abIl gene egoista\u00bb, 1976), Manzi immagina che figure aliene sbarchino sulla Terra per valutare se gli abitanti del nostro pianeta abbiano consapevolezza di s\u00e9 e delle proprie origini, in base a un unico parametro: aver compreso il fenomeno dell\u2019evoluzione. Le risposte vengono da alcuni manoscritti rinvenuti fra macerie pericolanti, nei quali compaiono il piccolo scheletro di australopiteco che tutti conosciamo come Lucy, e poi il ragazzo del Turkana, gli \u00abhobbit\u00bb dell\u2019isola di Flores, l\u2019uomo di Ceprano, i Neanderthal del Circeo e di Altamura, la mummia rinvenuta fra i ghiacci in Tirolo.<\/p>\n<p style=\"font-weight: 400;\">\u00c8 professore ordinario di Antropologia alla Sapienza Universit\u00e0 di Roma, accademico dei Lincei e accademico delle Scienze (o dei XL). La sua produzione scientifica internazionale spazia dai temi dell\u2019evoluzione umana a quelli della bioarcheologia. Editorialista di \u00abLe Scienze\u00bb, collabora con quotidiani, periodici, trasmissioni radio e tv. Fra i numerosi libri per il Mulino: \u00abUltime notizie sull\u2019evoluzione umana\u00bb (2017), \u00abIl grande racconto dell\u2019evoluzione umana\u00bb (2013 e 2018), \u00abL\u2019ultimo Neanderthal racconta\u00bb (2021).<\/p>\n<p>&nbsp;<\/p>\n<p><em>Ingresso gratuito fino ad esaurimento posti disponibili.\u00a0Per partecipare \u00e8 necessario scaricare il voucher gratuito dal sito <strong><u><a href=\"http:\/\/www.ticketone.it\/\" data-auth=\"Verified\">Ticketone.it<\/a><\/u>\u00a0<\/strong>o presso botteghino dell\u2019Auditorium Parco della Musica Ennio Morricone.\u00a0<strong>NOTA<\/strong>:\u00a0Il biglietto \u00e8 valido per l\u2019ingresso, con fila prioritaria,\u00a0<strong>entro e non <\/strong>oltre 10 minuti prima dall\u2019orario di inizio dell\u2019evento.\u00a0Trascorso tale termine il biglietto perde la sua validit\u00e0, e priorit\u00e0 in ingresso viene data a chi sia eventualmente in fila d\u2019attesa.<\/em><\/p>\n<p style=\"font-weight: 400; text-align: center;\">\n","protected":false},"excerpt":{"rendered":"Torna all\u2019Auditorium Parco della Musica Ennio Morricone dal 22 al 24 marzo 2024 Libri Come, la festa del Libro e della Lettura.","protected":false},"featured_media":14603,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[],"event_genre":[],"event_themes":[],"event_format":[74],"event_consigliati":[],"class_list":["post-13927","event","type-event","status-publish","has-post-thumbnail","hentry","event_format-festival"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giorgio Manzi \u2013 &quot;Antenati&quot; con Edoardo Camurri | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"description\" content=\"Torna all\u2019Auditorium Parco della Musica Ennio Morricone dal 22 al 24 marzo 2024 Libri Come, la festa del Libro e della Lettura.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/giorgio-manzi-antenati-con-edoardo-camurri\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giorgio Manzi \u2013 &quot;Antenati&quot; con Edoardo Camurri | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Torna all\u2019Auditorium Parco della Musica Ennio Morricone dal 22 al 24 marzo 2024 Libri Come, la festa del Libro e della Lettura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/giorgio-manzi-antenati-con-edoardo-camurri\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-14T12:54:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/03\/Foto-Giorgio-Manzi_1920X1080-700x394.png\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/giorgio-manzi-antenati-con-edoardo-camurri\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/giorgio-manzi-antenati-con-edoardo-camurri\\\/\",\"name\":\"Giorgio Manzi \u2013 \\\"Antenati\\\" con Edoardo Camurri | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/giorgio-manzi-antenati-con-edoardo-camurri\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/giorgio-manzi-antenati-con-edoardo-camurri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Foto-Giorgio-Manzi_1920X1080.png\",\"datePublished\":\"2024-03-06T09:23:24+00:00\",\"dateModified\":\"2024-03-14T12:54:16+00:00\",\"description\":\"Torna all\u2019Auditorium Parco della Musica Ennio Morricone dal 22 al 24 marzo 2024 Libri Come, la festa del Libro e della Lettura.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/giorgio-manzi-antenati-con-edoardo-camurri\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/giorgio-manzi-antenati-con-edoardo-camurri\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/giorgio-manzi-antenati-con-edoardo-camurri\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Foto-Giorgio-Manzi_1920X1080.png\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Foto-Giorgio-Manzi_1920X1080.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/giorgio-manzi-antenati-con-edoardo-camurri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giorgio Manzi \u2013 &#8220;Antenati&#8221; con Edoardo Camurri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giorgio Manzi \u2013 \"Antenati\" con Edoardo Camurri | Auditorium Parco della Musica Ennio Morricone","description":"Torna all\u2019Auditorium Parco della Musica Ennio Morricone dal 22 al 24 marzo 2024 Libri Come, la festa del Libro e della Lettura.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/giorgio-manzi-antenati-con-edoardo-camurri\/","og_locale":"it_IT","og_type":"article","og_title":"Giorgio Manzi \u2013 \"Antenati\" con Edoardo Camurri | Auditorium Parco della Musica Ennio Morricone","og_description":"Torna all\u2019Auditorium Parco della Musica Ennio Morricone dal 22 al 24 marzo 2024 Libri Come, la festa del Libro e della Lettura.","og_url":"https:\/\/www.auditorium.com\/it\/event\/giorgio-manzi-antenati-con-edoardo-camurri\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2024-03-14T12:54:16+00:00","og_image":[{"width":700,"height":394,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/03\/Foto-Giorgio-Manzi_1920X1080-700x394.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/giorgio-manzi-antenati-con-edoardo-camurri\/","url":"https:\/\/www.auditorium.com\/it\/event\/giorgio-manzi-antenati-con-edoardo-camurri\/","name":"Giorgio Manzi \u2013 \"Antenati\" con Edoardo Camurri | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/giorgio-manzi-antenati-con-edoardo-camurri\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/giorgio-manzi-antenati-con-edoardo-camurri\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/03\/Foto-Giorgio-Manzi_1920X1080.png","datePublished":"2024-03-06T09:23:24+00:00","dateModified":"2024-03-14T12:54:16+00:00","description":"Torna all\u2019Auditorium Parco della Musica Ennio Morricone dal 22 al 24 marzo 2024 Libri Come, la festa del Libro e della Lettura.","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/giorgio-manzi-antenati-con-edoardo-camurri\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/giorgio-manzi-antenati-con-edoardo-camurri\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/giorgio-manzi-antenati-con-edoardo-camurri\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/03\/Foto-Giorgio-Manzi_1920X1080.png","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/03\/Foto-Giorgio-Manzi_1920X1080.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/giorgio-manzi-antenati-con-edoardo-camurri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Giorgio Manzi \u2013 &#8220;Antenati&#8221; con Edoardo Camurri"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/13927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/14603"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=13927"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=13927"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=13927"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=13927"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=13927"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=13927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}