{"id":12065,"date":"2023-11-30T10:59:24","date_gmt":"2023-11-30T09:59:24","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=12065"},"modified":"2023-12-11T21:35:54","modified_gmt":"2023-12-11T20:35:54","slug":"come-onde-del-mare-incontri-senza-confini","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/come-onde-del-mare-incontri-senza-confini\/","title":{"rendered":"Come onde del mare: incontri senza confini"},"content":{"rendered":"<p>Dal <strong>21 dicembre al 21 gennaio<\/strong> all\u2019Auditorium Parco della Musica Ennio Morricone di Roma sar\u00e0 possibile visitare gratuitamente la mostra fotografica di <strong>Emergency<\/strong>, &#8220;Come onde del mare: incontri senza confini&#8221;.\u00a0In collaborazione con la <strong>Fondazione Musica per Roma<\/strong> l\u2019esposizione aprir\u00e0 il 21 dicembre alle ore 19.00 per raccontare il primo anno della\u00a0Life Support, la nave dell\u2019Ong che svolge attivit\u00e0 di ricerca e soccorso nel Mediterraneo centrale, una delle rotte migratorie pi\u00f9 pericolose al mondo.\u00a0I fenomeni migratori sono inarrestabili, come le onde. Ci spostiamo, da sempre, come le correnti marine. Siamo esseri animati dal desiderio e dalla necessit\u00e0 di avere una vita migliore, vivere in un Paese che garantisca diritti, dignit\u00e0, libert\u00e0. Un luogo dove sogni, aspirazioni, inclinazioni siano riconosciuti e curati.<span class=\"Apple-converted-space\">\u00a0<\/span>Siamo in cammino. I movimenti delle persone e dei popoli sono parte della storia dell\u2019umanit\u00e0. Non ci sono confini in grado di fermarli. E sono senza barriere anche gli incontri che le donne e gli uomini di <strong>Emergency\u00a0<\/strong>compiono in mare. Corpi che si toccano, sguardi che si riconoscono. Abbracci, pianti, sorrisi. L\u2019incontro con le persone che soccorriamo in mezzo al mare ci porta all\u2019essenza del nostro lavoro: aiutare chi ha bisogno, senza voltarsi dall\u2019altra parte. \u00c8 quello che <strong>Emergency\u00a0<\/strong>fa da quando \u00e8 stata fondata.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>La mostra racconta attraverso immagini, suoni e parole il lavoro di Emergency\u00a0nel Mediterraneo centrale, dove secondo l\u2019Organizzazione Internazionale per le Migrazioni (OIM) <b>sono oltre 22 mila le persone morte o disperse dal 2014. Una media di sei persone al giorno.<\/b> Una strage silenziosa contro cui <strong>Emergency\u00a0<\/strong>chiede una missione europea di ricerca e soccorso che tuteli la vita delle persone e sappia valorizzare anche il contributo della flotta civile, e vie legali e sicure di accesso all\u2019Europa. In mare dal dicembre del 2022, nel suo primo anno di attivit\u00e0 la Life Support di <strong>Emergency\u00a0<\/strong>ha tratto in salvo oltre 1.200 persone. Ognuna di esse ha portato all\u2019interno della nave la sua storia personale e le sue speranze.<span class=\"Apple-converted-space\">\u00a0<\/span>Attraverso l\u2019utilizzo di fotografie, video, suoni e testimonianze, \u00e8 stato creato un percorso immersivo per offrire al visitatore un\u2019esperienza completa che faccia comprendere cosa succede durante i salvataggi in mare, dal punto di vista delle persone soccorse e di chi soccorre. Inoltre in occasione dell\u2019apertura si potr\u00e0 salire virtualmente a bordo della nave Life Support di Emergency\u00a0grazie ai visori a 360\u00b0. <span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Il percorso si articoler\u00e0 attraverso le immagini di <strong>Giulio Piscitelli<\/strong>, <strong>Gabriele Micalizzi<\/strong>, <strong>Dario Bosio<\/strong>, <strong>Davide Preti<\/strong>, <strong>Francesco De Scisciolo<\/strong> e <strong>Giorgio Dirindin<\/strong>, i fotografi saliti a bordo negli scorsi mesi.\u00a0L\u2019allestimento \u00e8 stato curato e ideato da<b>The Buss<\/b>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>L\u2019esposizione effettuer\u00e0 i seguenti orari:\u00a0<\/strong><\/h3>\n<p>Dal luned\u00ec al venerd\u00ec apertura dalle ore 17.00 alle ore 21.00.<br \/>\nSabato e domenica: apertura dalle ore 11.00 alle ore 21.00.<br \/>\nNei festivi la mostra effettuer\u00e0 i seguenti orari:<br \/>\n8 e 26 dicembre: apertura ore 11.00 -21.00<br \/>\n24 e 31 dicembre: apertura ore 11.00 \u2013 17.00<br \/>\n25 dicembre e 1\u00b0 gennaio: apertura ore 17.00 -21.00<\/p>\n<p>&nbsp;<\/p>\n<p>Foto in evidenza di Giorgio Dirindin<\/p>\n","protected":false},"excerpt":{"rendered":"Dal 21 dicembre al 21 gennaio all\u2019Auditorium Parco della Musica Ennio Morricone di Roma sar\u00e0 possibile visitare gratuitamente la mostra fotografica di Emergency.","protected":false},"featured_media":12345,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[],"event_genre":[],"event_themes":[],"event_format":[78],"event_consigliati":[],"class_list":["post-12065","event","type-event","status-publish","has-post-thumbnail","hentry","event_format-mostre"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come onde del mare: incontri senza confini | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"description\" content=\"Dal 21 dicembre al 21 gennaio all\u2019Auditorium Parco della Musica Ennio Morricone di Roma sar\u00e0 possibile visitare gratuitamente la mostra fotografica di Emergency.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/come-onde-del-mare-incontri-senza-confini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come onde del mare: incontri senza confini | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Dal 21 dicembre al 21 gennaio all\u2019Auditorium Parco della Musica Ennio Morricone di Roma sar\u00e0 possibile visitare gratuitamente la mostra fotografica di Emergency.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/come-onde-del-mare-incontri-senza-confini\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-11T20:35:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/11\/Mostra-EMERGENCY-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/come-onde-del-mare-incontri-senza-confini\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/come-onde-del-mare-incontri-senza-confini\\\/\",\"name\":\"Come onde del mare: incontri senza confini | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/come-onde-del-mare-incontri-senza-confini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/come-onde-del-mare-incontri-senza-confini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Mostra-EMERGENCY-1.jpg\",\"datePublished\":\"2023-11-30T09:59:24+00:00\",\"dateModified\":\"2023-12-11T20:35:54+00:00\",\"description\":\"Dal 21 dicembre al 21 gennaio all\u2019Auditorium Parco della Musica Ennio Morricone di Roma sar\u00e0 possibile visitare gratuitamente la mostra fotografica di Emergency.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/come-onde-del-mare-incontri-senza-confini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/come-onde-del-mare-incontri-senza-confini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/come-onde-del-mare-incontri-senza-confini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Mostra-EMERGENCY-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Mostra-EMERGENCY-1.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/come-onde-del-mare-incontri-senza-confini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come onde del mare: incontri senza confini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come onde del mare: incontri senza confini | Auditorium Parco della Musica Ennio Morricone","description":"Dal 21 dicembre al 21 gennaio all\u2019Auditorium Parco della Musica Ennio Morricone di Roma sar\u00e0 possibile visitare gratuitamente la mostra fotografica di Emergency.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/come-onde-del-mare-incontri-senza-confini\/","og_locale":"it_IT","og_type":"article","og_title":"Come onde del mare: incontri senza confini | Auditorium Parco della Musica Ennio Morricone","og_description":"Dal 21 dicembre al 21 gennaio all\u2019Auditorium Parco della Musica Ennio Morricone di Roma sar\u00e0 possibile visitare gratuitamente la mostra fotografica di Emergency.","og_url":"https:\/\/www.auditorium.com\/it\/event\/come-onde-del-mare-incontri-senza-confini\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2023-12-11T20:35:54+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/11\/Mostra-EMERGENCY-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/come-onde-del-mare-incontri-senza-confini\/","url":"https:\/\/www.auditorium.com\/it\/event\/come-onde-del-mare-incontri-senza-confini\/","name":"Come onde del mare: incontri senza confini | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/come-onde-del-mare-incontri-senza-confini\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/come-onde-del-mare-incontri-senza-confini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/11\/Mostra-EMERGENCY-1.jpg","datePublished":"2023-11-30T09:59:24+00:00","dateModified":"2023-12-11T20:35:54+00:00","description":"Dal 21 dicembre al 21 gennaio all\u2019Auditorium Parco della Musica Ennio Morricone di Roma sar\u00e0 possibile visitare gratuitamente la mostra fotografica di Emergency.","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/come-onde-del-mare-incontri-senza-confini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/come-onde-del-mare-incontri-senza-confini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/come-onde-del-mare-incontri-senza-confini\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/11\/Mostra-EMERGENCY-1.jpg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/11\/Mostra-EMERGENCY-1.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/come-onde-del-mare-incontri-senza-confini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Come onde del mare: incontri senza confini"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/12065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/12345"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=12065"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=12065"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=12065"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=12065"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=12065"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=12065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}