{"id":10833,"date":"2023-10-09T08:44:44","date_gmt":"2023-10-09T06:44:44","guid":{"rendered":"https:\/\/www.auditorium.com\/?post_type=event&#038;p=10833"},"modified":"2023-10-10T21:41:29","modified_gmt":"2023-10-10T19:41:29","slug":"christian-greco","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/christian-greco\/","title":{"rendered":"Christian Greco \u2013 &#8220;Gli antichi egizi e l\u2019aldil\u00e0&#8221;"},"content":{"rendered":"<p>Abbiamo una conoscenza approfondita di come la civilt\u00e0 egizia intendesse i destini dell\u2019uomo dopo la morte: i Libri dell\u2019Aldil\u00e0 \u2013 in una combinazione di testo e immagini strettamente correlati \u2013 descrivono il mondo sotterraneo; forniscono al sovrano defunto la conoscenza necessaria per sopravvivere in compagnia con gli dei e ricordano a noi come gli Antichi Egizi intendessero il viaggio del Sole e l\u2019intero universo.<\/p>\n<p><strong>Christian Greco<\/strong> \u00e8 Direttore del Museo Egizio di Torino dal 2014. Formatosi principalmente in Olanda, \u00e8 un egittologo con una grande esperienza in ambito museale: ha curato moltissimi progetti espositivi e di curatela in\u00a0Olanda,\u00a0Giappone,\u00a0Finlandia,\u00a0Spagna\u00a0e\u00a0Scozia. Alla direzione del Museo Egizio ha sviluppato importanti collaborazioni internazionali con musei, universit\u00e0 ed istituti di ricerca di tutto il mondo. Al suo attivo ha molteplici pubblicazioni divulgative e scientifiche in diverse lingue e numerose partecipazioni a convegni internazionali di egittologia e di museologia.<\/p>\n","protected":false},"excerpt":{"rendered":"&#8220;I confini del mondo&#8221; \u00e8 il nuovo ciclo delle Lezioni di Storia degli Editori Laterza all&#8217;Auditorium Parco della Musica Ennio Morricone di Roma, dal 12 novembre 2023 al 7 aprile 2024.","protected":false},"featured_media":10894,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[],"event_genre":[],"event_themes":[],"event_format":[73],"event_consigliati":[],"class_list":["post-10833","event","type-event","status-publish","has-post-thumbnail","hentry","event_format-lezioni"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Christian Greco \u2013 &quot;Gli antichi egizi e l\u2019aldil\u00e0&quot; | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"description\" content=\"&quot;I confini del mondo&quot; \u00e8 il nuovo ciclo delle Lezioni di Storia degli Editori Laterza all&#039;Auditorium Parco della Musica Ennio Morricone di Roma, dal 12 novembre 2023 al 7 aprile 2024.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/christian-greco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Christian Greco \u2013 &quot;Gli antichi egizi e l\u2019aldil\u00e0&quot; | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"&quot;I confini del mondo&quot; \u00e8 il nuovo ciclo delle Lezioni di Storia degli Editori Laterza all&#039;Auditorium Parco della Musica Ennio Morricone di Roma, dal 12 novembre 2023 al 7 aprile 2024.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/christian-greco\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-10T19:41:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/10\/lezioni-di-storia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/christian-greco\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/christian-greco\\\/\",\"name\":\"Christian Greco \u2013 \\\"Gli antichi egizi e l\u2019aldil\u00e0\\\" | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/christian-greco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/christian-greco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/lezioni-di-storia.png\",\"datePublished\":\"2023-10-09T06:44:44+00:00\",\"dateModified\":\"2023-10-10T19:41:29+00:00\",\"description\":\"\\\"I confini del mondo\\\" \u00e8 il nuovo ciclo delle Lezioni di Storia degli Editori Laterza all'Auditorium Parco della Musica Ennio Morricone di Roma, dal 12 novembre 2023 al 7 aprile 2024.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/christian-greco\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/christian-greco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/christian-greco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/lezioni-di-storia.png\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/lezioni-di-storia.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/christian-greco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Christian Greco \u2013 &#8220;Gli antichi egizi e l\u2019aldil\u00e0&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Christian Greco \u2013 \"Gli antichi egizi e l\u2019aldil\u00e0\" | Auditorium Parco della Musica Ennio Morricone","description":"\"I confini del mondo\" \u00e8 il nuovo ciclo delle Lezioni di Storia degli Editori Laterza all'Auditorium Parco della Musica Ennio Morricone di Roma, dal 12 novembre 2023 al 7 aprile 2024.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/christian-greco\/","og_locale":"it_IT","og_type":"article","og_title":"Christian Greco \u2013 \"Gli antichi egizi e l\u2019aldil\u00e0\" | Auditorium Parco della Musica Ennio Morricone","og_description":"\"I confini del mondo\" \u00e8 il nuovo ciclo delle Lezioni di Storia degli Editori Laterza all'Auditorium Parco della Musica Ennio Morricone di Roma, dal 12 novembre 2023 al 7 aprile 2024.","og_url":"https:\/\/www.auditorium.com\/it\/event\/christian-greco\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2023-10-10T19:41:29+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/10\/lezioni-di-storia.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/christian-greco\/","url":"https:\/\/www.auditorium.com\/it\/event\/christian-greco\/","name":"Christian Greco \u2013 \"Gli antichi egizi e l\u2019aldil\u00e0\" | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/christian-greco\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/christian-greco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/10\/lezioni-di-storia.png","datePublished":"2023-10-09T06:44:44+00:00","dateModified":"2023-10-10T19:41:29+00:00","description":"\"I confini del mondo\" \u00e8 il nuovo ciclo delle Lezioni di Storia degli Editori Laterza all'Auditorium Parco della Musica Ennio Morricone di Roma, dal 12 novembre 2023 al 7 aprile 2024.","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/christian-greco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/christian-greco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/christian-greco\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/10\/lezioni-di-storia.png","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/10\/lezioni-di-storia.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/christian-greco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Christian Greco \u2013 &#8220;Gli antichi egizi e l\u2019aldil\u00e0&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/10833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/10894"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=10833"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=10833"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=10833"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=10833"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=10833"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=10833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}