{"id":1010,"date":"2022-12-28T10:18:33","date_gmt":"2022-12-28T09:18:33","guid":{"rendered":"https:\/\/www.auditorium.com\/it\/?post_type=event&#038;p=1010"},"modified":"2023-04-06T16:10:42","modified_gmt":"2023-04-06T15:10:42","slug":"paolo-conte","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/it\/event\/paolo-conte\/","title":{"rendered":"Paolo Conte"},"content":{"rendered":"<p>Dopo i due sold out della scorsa estate, <strong>Paolo Conte<\/strong> torna il 6 giugno alla Cavea dell\u2019Auditorium Parco della Musica Ennio Morricone per l\u2019evento di apertura del Roma Summer Fest 2023.<\/p>\n<p>Uno spettacolo imperdibile in cui l\u2019irresistibile charme e l\u2019inconfondibile timbro vocale di Paolo Conte saranno accompagnati da un ensemble orchestrale di undici musicisti eccezionali: <strong>Nunzio Barbieri<\/strong> (chitarre), <strong>Lucio Caliendo<\/strong> (oboe, fagotto), <strong>Claudio<\/strong> <strong>Chiara<\/strong> (sax contralto, flauto, fisarmonica, tastiere), <strong>Daniele Dall\u2019Omo<\/strong> (chitarre), <strong>Daniele Di Gregorio<\/strong> (batteria, percussioni, marimba), <strong>Luca Enipeo<\/strong> (chitarre), <strong>Francesca Gosio<\/strong> (violoncello), <strong>Massimo Pitzianti<\/strong> (fisarmonica, bandoneon, sax baritono, piano, tastiere), <strong>Piergiorgio Rosso<\/strong> (violino), <strong>Pierre Steve Jino Touche<\/strong> (contrabbasso) e <strong>Luca<\/strong> <strong>Velotti<\/strong> (sax soprano, sax tenore, flauto, clarinetto).<\/p>\n<p>In programma i brani pi\u00f9 amati del cantautore, eseguiti nella splendida cornice dell\u2019Auditorium Parco della Musica Ennio Morricone: \u201cHemingway\u201d, \u201cSotto le stelle del jazz\u201d, \u201cCome Di\u201d, \u201cAlle prese con una verde milonga\u201d, \u201cAguaplano\u201d, \u201cMax\u201d, \u201cGioco d\u2019azzardo\u201d, \u201cDancing\u201d, \u201cMadeleine\u201d, \u201cGenova per noi\u201d, \u201cVia con me\u201d, \u201cReveries\u201d, \u201cGli impermeabili\u201d e \u201cLe chic et le charme\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"Uno spettacolo imperdibile in cui l\u2019irresistibile charme e l\u2019inconfondibile timbro vocale di Paolo Conte saranno accompagnati da un ensemble orchestrale di undici musicisti eccezionali.","protected":false},"featured_media":1051,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[4],"event_genre":[63],"event_themes":[],"event_format":[74],"event_consigliati":[],"class_list":["post-1010","event","type-event","status-publish","has-post-thumbnail","hentry","event_categories-musica","event_genre-autore","event_format-festival"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paolo Conte | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"description\" content=\"Paolo Conte torna il 6 giugno 2023 alll\u2019Auditorium Parco della Musica per l&#039;apertura del Roma Summer Fest 2023. Scopri di pi\u00f9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/it\/event\/paolo-conte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paolo Conte | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Paolo Conte torna il 6 giugno 2023 alll\u2019Auditorium Parco della Musica per l&#039;apertura del Roma Summer Fest 2023. Scopri di pi\u00f9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/it\/event\/paolo-conte\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-06T15:10:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/Paolo-Conte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/paolo-conte\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/paolo-conte\\\/\",\"name\":\"Paolo Conte | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/paolo-conte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/paolo-conte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Paolo-Conte.jpg\",\"datePublished\":\"2022-12-28T09:18:33+00:00\",\"dateModified\":\"2023-04-06T15:10:42+00:00\",\"description\":\"Paolo Conte torna il 6 giugno 2023 alll\u2019Auditorium Parco della Musica per l'apertura del Roma Summer Fest 2023. Scopri di pi\u00f9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/paolo-conte\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/paolo-conte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/paolo-conte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Paolo-Conte.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Paolo-Conte.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Paolo Conte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/event\\\/paolo-conte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paolo Conte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paolo Conte | Auditorium Parco della Musica Ennio Morricone","description":"Paolo Conte torna il 6 giugno 2023 alll\u2019Auditorium Parco della Musica per l'apertura del Roma Summer Fest 2023. Scopri di pi\u00f9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/it\/event\/paolo-conte\/","og_locale":"it_IT","og_type":"article","og_title":"Paolo Conte | Auditorium Parco della Musica Ennio Morricone","og_description":"Paolo Conte torna il 6 giugno 2023 alll\u2019Auditorium Parco della Musica per l'apertura del Roma Summer Fest 2023. Scopri di pi\u00f9.","og_url":"https:\/\/www.auditorium.com\/it\/event\/paolo-conte\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2023-04-06T15:10:42+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/Paolo-Conte.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/it\/event\/paolo-conte\/","url":"https:\/\/www.auditorium.com\/it\/event\/paolo-conte\/","name":"Paolo Conte | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/it\/event\/paolo-conte\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/event\/paolo-conte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/Paolo-Conte.jpg","datePublished":"2022-12-28T09:18:33+00:00","dateModified":"2023-04-06T15:10:42+00:00","description":"Paolo Conte torna il 6 giugno 2023 alll\u2019Auditorium Parco della Musica per l'apertura del Roma Summer Fest 2023. Scopri di pi\u00f9.","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/it\/event\/paolo-conte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/it\/event\/paolo-conte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/event\/paolo-conte\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/Paolo-Conte.jpg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/Paolo-Conte.jpg","width":1920,"height":1080,"caption":"Paolo Conte"},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/it\/event\/paolo-conte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/it\/"},{"@type":"ListItem","position":2,"name":"Paolo Conte"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/it\/#website","url":"https:\/\/www.auditorium.com\/it\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Progettato da Renzo Piano, l&#039;Auditorium rappresenta una sofisticata architettura musicale e uno straordinario intervento di riqualificazione urbana.","publisher":{"@id":"https:\/\/www.auditorium.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/it\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event\/1010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media\/1051"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/media?parent=1010"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_categories?post=1010"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_genre?post=1010"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_themes?post=1010"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_format?post=1010"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/it\/wp-json\/wp\/v2\/event_consigliati?post=1010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}