{"id":7259,"date":"2023-05-08T09:28:49","date_gmt":"2023-05-08T08:28:49","guid":{"rendered":"https:\/\/www.auditorium.com\/event\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\/"},"modified":"2023-05-08T09:28:49","modified_gmt":"2023-05-08T08:28:49","slug":"natale-con-il-coro-di-voci-bianche-e-la-cantoria","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/en\/event\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\/","title":{"rendered":"Natale con il Coro di Voci Bianche e la Cantoria"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":7257,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[120],"event_genre":[109],"event_themes":[],"event_format":[],"event_consigliati":[],"class_list":["post-7259","event","type-event","status-publish","has-post-thumbnail","hentry","event_categories-classic","event_genre-classic"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Natale con il Coro di Voci Bianche e la Cantoria | Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/en\/event\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Natale con il Coro di Voci Bianche e la Cantoria | Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/en\/event\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/05\/education-natale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"955\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\\\/\",\"name\":\"Natale con il Coro di Voci Bianche e la Cantoria | Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/education-natale.jpg\",\"datePublished\":\"2023-05-08T08:28:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/education-natale.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/education-natale.jpg\",\"width\":1920,\"height\":955},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Natale con il Coro di Voci Bianche e la Cantoria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Il pi\u00f9 grande luogo di spettacolo in Europa\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Natale con il Coro di Voci Bianche e la Cantoria | Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/en\/event\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\/","og_locale":"en_US","og_type":"article","og_title":"Natale con il Coro di Voci Bianche e la Cantoria | Auditorium Parco della Musica Ennio Morricone","og_url":"https:\/\/www.auditorium.com\/en\/event\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","og_image":[{"width":1920,"height":955,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/05\/education-natale.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/en\/event\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\/","url":"https:\/\/www.auditorium.com\/en\/event\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\/","name":"Natale con il Coro di Voci Bianche e la Cantoria | Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/en\/event\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/en\/event\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/05\/education-natale.jpg","datePublished":"2023-05-08T08:28:49+00:00","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/en\/event\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/en\/event\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.auditorium.com\/en\/event\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/05\/education-natale.jpg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/05\/education-natale.jpg","width":1920,"height":955},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/en\/event\/natale-con-il-coro-di-voci-bianche-e-la-cantoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/en\/"},{"@type":"ListItem","position":2,"name":"Natale con il Coro di Voci Bianche e la Cantoria"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/en\/#website","url":"https:\/\/www.auditorium.com\/en\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Il pi\u00f9 grande luogo di spettacolo in Europa","publisher":{"@id":"https:\/\/www.auditorium.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/en\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.auditorium.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event\/7259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/media\/7257"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/media?parent=7259"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event_categories?post=7259"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event_genre?post=7259"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event_themes?post=7259"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event_format?post=7259"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event_consigliati?post=7259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}