{"id":5944,"date":"2023-03-27T11:28:01","date_gmt":"2023-03-27T09:28:01","guid":{"rendered":"https:\/\/www.auditorium.com\/event\/asaf-avidan-2\/"},"modified":"2023-04-27T13:25:21","modified_gmt":"2023-04-27T12:25:21","slug":"asaf-avidan-2","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/en\/event\/asaf-avidan-2\/","title":{"rendered":"Asaf Avidan"},"content":{"rendered":"<p>Five years after his last solo performance, <strong>Asaf Avidan <\/strong> announces an unmissable concert on Nov. 7 at the Auditorium Parco della Musica Ennio Morricone as part of his Ichnology Solo Tour, a series of select solo performances in which his undisputed talent will take center stage amid intimate ballads, charismatic and engaging storytelling, and the energy of a one-of-a-kind artist.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"Five years after his last solo performance, Asaf Avidan announces an unmissable live performance at the Auditorium Parco della Musica Ennio Morricone.","protected":false},"featured_media":5931,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[116],"event_genre":[117],"event_themes":[],"event_format":[],"event_consigliati":[],"class_list":["post-5944","event","type-event","status-publish","has-post-thumbnail","hentry","event_categories-pop-rock-en","event_genre-pop-rock-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Asaf Avidan | Auditorium Parco della Musica Ennio Morricone%<\/title>\n<meta name=\"description\" content=\"Five years after his last solo performance, Asaf Avidan announces an unmissable live performance at the Auditorium Parco della Musica Ennio Morricone.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/en\/event\/asaf-avidan-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asaf Avidan | Auditorium Parco della Musica Ennio Morricone%\" \/>\n<meta property=\"og:description\" content=\"Five years after his last solo performance, Asaf Avidan announces an unmissable live performance at the Auditorium Parco della Musica Ennio Morricone.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/en\/event\/asaf-avidan-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-27T12:25:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/03\/Asaf-Avidan.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/asaf-avidan-2\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/asaf-avidan-2\\\/\",\"name\":\"Asaf Avidan | Auditorium Parco della Musica Ennio Morricone%\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/asaf-avidan-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/asaf-avidan-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Asaf-Avidan.png\",\"datePublished\":\"2023-03-27T09:28:01+00:00\",\"dateModified\":\"2023-04-27T12:25:21+00:00\",\"description\":\"Five years after his last solo performance, Asaf Avidan announces an unmissable live performance at the Auditorium Parco della Musica Ennio Morricone.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/asaf-avidan-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/asaf-avidan-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/asaf-avidan-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Asaf-Avidan.png\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Asaf-Avidan.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/asaf-avidan-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asaf Avidan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Il pi\u00f9 grande luogo di spettacolo in Europa\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asaf Avidan | Auditorium Parco della Musica Ennio Morricone%","description":"Five years after his last solo performance, Asaf Avidan announces an unmissable live performance at the Auditorium Parco della Musica Ennio Morricone.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/en\/event\/asaf-avidan-2\/","og_locale":"en_US","og_type":"article","og_title":"Asaf Avidan | Auditorium Parco della Musica Ennio Morricone%","og_description":"Five years after his last solo performance, Asaf Avidan announces an unmissable live performance at the Auditorium Parco della Musica Ennio Morricone.","og_url":"https:\/\/www.auditorium.com\/en\/event\/asaf-avidan-2\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2023-04-27T12:25:21+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/03\/Asaf-Avidan.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/en\/event\/asaf-avidan-2\/","url":"https:\/\/www.auditorium.com\/en\/event\/asaf-avidan-2\/","name":"Asaf Avidan | Auditorium Parco della Musica Ennio Morricone%","isPartOf":{"@id":"https:\/\/www.auditorium.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/en\/event\/asaf-avidan-2\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/en\/event\/asaf-avidan-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/03\/Asaf-Avidan.png","datePublished":"2023-03-27T09:28:01+00:00","dateModified":"2023-04-27T12:25:21+00:00","description":"Five years after his last solo performance, Asaf Avidan announces an unmissable live performance at the Auditorium Parco della Musica Ennio Morricone.","breadcrumb":{"@id":"https:\/\/www.auditorium.com\/en\/event\/asaf-avidan-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/en\/event\/asaf-avidan-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.auditorium.com\/en\/event\/asaf-avidan-2\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/03\/Asaf-Avidan.png","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/03\/Asaf-Avidan.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.auditorium.com\/en\/event\/asaf-avidan-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.auditorium.com\/en\/"},{"@type":"ListItem","position":2,"name":"Asaf Avidan"}]},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/en\/#website","url":"https:\/\/www.auditorium.com\/en\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Il pi\u00f9 grande luogo di spettacolo in Europa","publisher":{"@id":"https:\/\/www.auditorium.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/en\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.auditorium.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event\/5944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/media\/5931"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/media?parent=5944"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event_categories?post=5944"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event_genre?post=5944"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event_themes?post=5944"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event_format?post=5944"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event_consigliati?post=5944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}