{"id":15731,"date":"2024-04-17T14:00:25","date_gmt":"2024-04-17T13:00:25","guid":{"rendered":"https:\/\/www.auditorium.com\/event\/concerto-finale-corso-di-tromba-3\/"},"modified":"2024-04-17T14:00:29","modified_gmt":"2024-04-17T13:00:29","slug":"15731","status":"publish","type":"event","link":"https:\/\/www.auditorium.com\/en\/event\/15731\/","title":{"rendered":""},"content":{"rendered":"<p>Accademia Nazionale di Santa Cecilia &#8211; Corsi di Perfezionamento<\/p>\n","protected":false},"excerpt":{"rendered":"Accademia Nazionale di Santa Cecilia &#8211; Corsi di Perfezionamento","protected":false},"featured_media":15729,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"event_categories":[56],"event_genre":[60],"event_themes":[],"event_format":[75],"event_consigliati":[],"class_list":["post-15731","event","type-event","status-publish","has-post-thumbnail","hentry","event_categories-musica-classica","event_genre-classica","event_format-rassegne"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>| Auditorium Parco della Musica Ennio Morricone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.auditorium.com\/en\/event\/15731\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"| Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"og:description\" content=\"Accademia Nazionale di Santa Cecilia &#8211; Corsi di Perfezionamento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.auditorium.com\/en\/event\/15731\/\" \/>\n<meta property=\"og:site_name\" content=\"Auditorium Parco della Musica Ennio Morricone\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-17T13:00:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/02\/auditorium-parco-della-musica-roma.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@auditoriumpdm\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/15731\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/15731\\\/\",\"name\":\"| Auditorium Parco della Musica Ennio Morricone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/15731\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/15731\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/tromba-scaled-1.jpg\",\"datePublished\":\"2024-04-17T13:00:25+00:00\",\"dateModified\":\"2024-04-17T13:00:29+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/15731\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/event\\\/15731\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/tromba-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/tromba-scaled-1.jpg\",\"width\":2560,\"height\":1274},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"description\":\"Il pi\u00f9 grande luogo di spettacolo in Europa\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/#organization\",\"name\":\"Auditorium Parco della Musica Ennio Morricone\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"contentUrl\":\"https:\\\/\\\/www.auditorium.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-auditorium.svg\",\"width\":86,\"height\":79,\"caption\":\"Auditorium Parco della Musica Ennio Morricone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.auditorium.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AuditoriumParcodellaMusica\",\"https:\\\/\\\/x.com\\\/auditoriumpdm\",\"https:\\\/\\\/www.instagram.com\\\/auditoriumparcodellamusica\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"| Auditorium Parco della Musica Ennio Morricone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.auditorium.com\/en\/event\/15731\/","og_locale":"en_US","og_type":"article","og_title":"| Auditorium Parco della Musica Ennio Morricone","og_description":"Accademia Nazionale di Santa Cecilia &#8211; Corsi di Perfezionamento","og_url":"https:\/\/www.auditorium.com\/en\/event\/15731\/","og_site_name":"Auditorium Parco della Musica Ennio Morricone","article_publisher":"https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","article_modified_time":"2024-04-17T13:00:29+00:00","og_image":[{"width":2048,"height":1152,"url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2023\/02\/auditorium-parco-della-musica-roma.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@auditoriumpdm","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.auditorium.com\/en\/event\/15731\/","url":"https:\/\/www.auditorium.com\/en\/event\/15731\/","name":"| Auditorium Parco della Musica Ennio Morricone","isPartOf":{"@id":"https:\/\/www.auditorium.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.auditorium.com\/en\/event\/15731\/#primaryimage"},"image":{"@id":"https:\/\/www.auditorium.com\/en\/event\/15731\/#primaryimage"},"thumbnailUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/04\/tromba-scaled-1.jpg","datePublished":"2024-04-17T13:00:25+00:00","dateModified":"2024-04-17T13:00:29+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.auditorium.com\/en\/event\/15731\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.auditorium.com\/en\/event\/15731\/#primaryimage","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/04\/tromba-scaled-1.jpg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2024\/04\/tromba-scaled-1.jpg","width":2560,"height":1274},{"@type":"WebSite","@id":"https:\/\/www.auditorium.com\/en\/#website","url":"https:\/\/www.auditorium.com\/en\/","name":"Auditorium Parco della Musica Ennio Morricone","description":"Il pi\u00f9 grande luogo di spettacolo in Europa","publisher":{"@id":"https:\/\/www.auditorium.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.auditorium.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.auditorium.com\/en\/#organization","name":"Auditorium Parco della Musica Ennio Morricone","url":"https:\/\/www.auditorium.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.auditorium.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","contentUrl":"https:\/\/www.auditorium.com\/wp-content\/uploads\/2022\/12\/logo-auditorium.svg","width":86,"height":79,"caption":"Auditorium Parco della Musica Ennio Morricone"},"image":{"@id":"https:\/\/www.auditorium.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AuditoriumParcodellaMusica","https:\/\/x.com\/auditoriumpdm","https:\/\/www.instagram.com\/auditoriumparcodellamusica\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event\/15731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/media\/15729"}],"wp:attachment":[{"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/media?parent=15731"}],"wp:term":[{"taxonomy":"event_categories","embeddable":true,"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event_categories?post=15731"},{"taxonomy":"event_genre","embeddable":true,"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event_genre?post=15731"},{"taxonomy":"event_themes","embeddable":true,"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event_themes?post=15731"},{"taxonomy":"event_format","embeddable":true,"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event_format?post=15731"},{"taxonomy":"event_consigliati","embeddable":true,"href":"https:\/\/www.auditorium.com\/en\/wp-json\/wp\/v2\/event_consigliati?post=15731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}